{"id":1437,"date":"2024-01-02T12:55:53","date_gmt":"2024-01-02T11:55:53","guid":{"rendered":"https:\/\/ecoturbino.eu\/?page_id=1437"},"modified":"2026-01-18T11:36:29","modified_gmt":"2026-01-18T10:36:29","slug":"historia-do-produto","status":"publish","type":"page","link":"https:\/\/ecoturbino.world\/pt\/product-history\/","title":{"rendered":"Hist\u00f3ria do produto ecoturbino\u00ae."},"content":{"rendered":"<div class=\"banner has-hover\" id=\"banner-593097200\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <img decoding=\"async\" width=\"2000\" height=\"230\" src=\"https:\/\/ecoturbino.world\/wp-content\/uploads\/2024\/01\/wasser-faq-2000-sw.webp\" class=\"bg attachment-original size-original\" alt=\"Cabe\u00e7alho de \u00e1gua\" \/>                        <div class=\"overlay\"><\/div>            \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n   <div id=\"text-box-375937044\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n<h1 class=\"uppercase\">hist\u00f3ria do ecoturbino<\/h1>\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-375937044 {\n  width: 91%;\n}\n#text-box-375937044 .text-box-content {\n  font-size: 100%;\n}\n@media (min-width:550px) {\n  #text-box-375937044 {\n    width: 56%;\n  }\n}\n@media (min-width:850px) {\n  #text-box-375937044 {\n    width: 69%;\n  }\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-593097200 {\n  padding-top: 110px;\n}\n#banner-593097200 .overlay {\n  background-color: rgba(0, 0, 0, 0.25);\n}\n#banner-593097200 .banner-bg img {\n  object-position: 41% 58%;\n}\n@media (min-width:550px) {\n  #banner-593097200 {\n    padding-top: 170px;\n  }\n}\n@media (min-width:850px) {\n  #banner-593097200 {\n    padding-top: 190px;\n  }\n}\n<\/style>\n  <\/div>\n\n\n<div class=\"row\"  id=\"row-340780808\">\n\n\t<div id=\"col-1220216643\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<h2 class=\"headlinefocus\">Breve informa\u00e7\u00e3o sobre o desenvolvimento da marca ecoturbino\u00ae e a liga\u00e7\u00e3o em rede com a Webdeals Shops GmbH<\/h2>\n<p>O ecoturbino, primeiro\u00a0<strong>conceptualizado e desenvolvido pelo Ing. Werner Krenek em 2005<\/strong>A Kerneck, uma empresa de engenharia de instrumenta\u00e7\u00e3o, \u00e9 um testemunho de mais de 30 anos de experi\u00eancia como engenheiro de instrumenta\u00e7\u00e3o. A vis\u00e3o da Kerneck foi impulsionada pela necessidade de uma solu\u00e7\u00e3o de poupan\u00e7a de \u00e1gua e de sa\u00fade, especificamente concebida para centros m\u00e9dicos na Alemanha e na \u00c1ustria.<\/p>\n<p>Este<strong>\u00a0sistema inovador, meticulosamente elaborado com um design de alta precis\u00e3o e utilizando ligas met\u00e1licas de qualidade superior<\/strong>O sistema de gest\u00e3o de \u00e1gua da T\u00dcV, Inc., aborda a necessidade cr\u00edtica de conserva\u00e7\u00e3o da \u00e1gua em instala\u00e7\u00f5es m\u00e9dicas. A sua cria\u00e7\u00e3o foi objeto de testes rigorosos e de certifica\u00e7\u00e3o pelos laborat\u00f3rios austr\u00edacos T\u00dcV, que confirmam as suas alega\u00e7\u00f5es de desempenho.<\/p>\n<p>Apesar das tentativas de outros para reproduzir o ecoturbino, nenhum conseguiu igualar as suas carater\u00edsticas distintas e o seu desempenho sem paralelo. O seu design \u00fanico e a sua efici\u00eancia solidificam a sua posi\u00e7\u00e3o como uma solu\u00e7\u00e3o pioneira na tecnologia de poupan\u00e7a de \u00e1gua, particularmente em ambientes m\u00e9dicos.<\/p>\n<h3>Resumo ou curriculum vitae dos produtos ecoturbino\u00ae complementado com datas anuais<\/h3>\n<p>Os produtos economizadores de \u00e1gua para hot\u00e9is, etc., que foram experimentados e testados na pr\u00e1tica, podem agora contar com muitos anos de desenvolvimento, testes e ensaios. Resumimos aqui os dados mais importantes para si.<\/p>\n\t<div id=\"gap-1978995056\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1978995056 {\n  padding-top: 15px;\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"is-divider divider clearfix\" style=\"max-width:100%;height:1px;\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\n\t<section class=\"section\" id=\"section_83093802\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row\"  id=\"row-421603672\">\n\n\t<div id=\"col-26525953\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<div class=\"row row-collapse align-equal\"  id=\"row-1966393851\">\n\n\t<div id=\"col-1541672910\" class=\"col medium-5 small-12 large-5\"  data-animate=\"bounceInUp\">\n\t\t\t\t<div class=\"col-inner box-shadow-2\"  >\n\t\t\t\n\t\t\t\n<div class=\"row row-collapse\"  id=\"row-1471317934\">\n\n\t<div id=\"col-1177291285\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner dark\" style=\"background-color:rgb(0, 139, 153);\" >\n\t\t\t\n\t\t\t\n<h3>2025<\/h3>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1943547645\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\" style=\"background-color:rgb(255,255,255);\" >\n\t\t\t\n\t\t\t\n<ul>\n<li>Desenvolvimento dos sistemas de duche ecoturbino plus com filtro de \u00e1gua: 3 sistemas: <a href=\"https:\/\/ecoturbino.shop\/shower-systems-water-filters\/\" target=\"_blank\" rel=\"noopener\">ecoturbino cl\u00ednica+, corpo+ e hotel+<\/a><\/li>\n<li>Sucesso do Grupo Johannesbad: Poupan\u00e7a sustent\u00e1vel de \u00e1gua em Bad F\u00fcssing de 73.000 m\u00b3 anuais com o ecoturbino <a href=\"https:\/\/ecoturbino.shop\/johannesbad-group-sustainability-facts\/\" target=\"_blank\" rel=\"noopener\">600 Chuveiros Relat\u00f3rio de sucesso<\/a> com factos e n\u00fameros de 6 anos<\/li>\n<\/ul>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<style>\n#row-1471317934 > .col > .col-inner {\n  padding: 10px 20px 2px 20px;\n}\n<\/style>\n<\/div>\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1541672910 > .col-inner {\n  margin: 0px 0px 25px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-80284872\" class=\"col medium-2 small-12 large-2 small-col-first\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t<div class=\"is-border is-dashed\"\n\t\tstyle=\"border-color:rgb(228, 228, 228);border-width:0px 2px 0px 0px;margin:60px 50% 0px 0px;\">\n\t<\/div>\n\t\t\t\n\n\t\t<div class=\"icon-box featured-box icon-box-center text-center\"  >\n\t\t\t\t\t<div class=\"icon-box-img has-icon-bg\" style=\"width: 60px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" style=\"border-width:3px;color:rgb(0, 139, 153);\">\n\t\t\t\t\t\t<?xml version=\"1.0\" encoding=\"UTF-8\"?>\n<!-- Generated by IcoMoon.io -->\n<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" version=\"1.1\" width=\"16\" height=\"16\" viewbox=\"0 0 16 16\">\n  <path fill=\"#000000\" d=\"M12.531 3.654c1.923 1.387 2.112 5.737 2.49 7.061l-3.58 1.419c-0.365-2.396-3.45-4.193-3.576-6.841s2.743-3.026 4.666-1.639zM14.707 15.822c-2.858 1.039-3.026-2.806-3.026-2.806l3.72-1.513c0 0 1.734 3.436-0.694 4.319zM0.034 2.985c0.379-2.341 2.675-4.101 4.458-2.14s0.872 5.414 2.308 7.365l-3.534 1.528c-0.669-1.204-3.611-4.413-3.232-6.754zM7.1 13.127c-2.34 1.092-3.544-2.564-3.544-2.564l3.7-1.56c0 0 2.599 2.838-0.156 4.124z\"><\/path>\n<\/svg>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n\t<div id=\"gap-172437750\" class=\"gap-element clearfix hidden\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-172437750 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n<div class=\"row row-collapse align-equal align-right\"  id=\"row-1744990806\">\n\n\t<div id=\"col-1298463285\" class=\"col medium-2 small-12 large-2\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t<div class=\"is-border is-dashed\"\n\t\tstyle=\"border-color:rgb(228, 228, 228);border-width:0px 2px 0px 0px;margin:60px 50% 0px 0px;\">\n\t<\/div>\n\t\t\t\n\n\t\t<div class=\"icon-box featured-box icon-box-center text-center\"  >\n\t\t\t\t\t<div class=\"icon-box-img has-icon-bg\" style=\"width: 60px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" style=\"border-width:3px;color:rgb(251, 201, 51);\">\n\t\t\t\t\t\t<?xml version=\"1.0\" encoding=\"UTF-8\"?>\n<!-- Generated by IcoMoon.io -->\n<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" version=\"1.1\" width=\"16\" height=\"16\" viewbox=\"0 0 16 16\">\n  <path fill=\"#000000\" d=\"M12.531 3.654c1.923 1.387 2.112 5.737 2.49 7.061l-3.58 1.419c-0.365-2.396-3.45-4.193-3.576-6.841s2.743-3.026 4.666-1.639zM14.707 15.822c-2.858 1.039-3.026-2.806-3.026-2.806l3.72-1.513c0 0 1.734 3.436-0.694 4.319zM0.034 2.985c0.379-2.341 2.675-4.101 4.458-2.14s0.872 5.414 2.308 7.365l-3.534 1.528c-0.669-1.204-3.611-4.413-3.232-6.754zM7.1 13.127c-2.34 1.092-3.544-2.564-3.544-2.564l3.7-1.56c0 0 2.599 2.838-0.156 4.124z\"><\/path>\n<\/svg>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n\t<div id=\"gap-475459086\" class=\"gap-element clearfix hidden\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-475459086 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-106673445\" class=\"col medium-5 small-12 large-5\"  data-animate=\"bounceInUp\">\n\t\t\t\t<div class=\"col-inner box-shadow-2\"  >\n\t\t\t\n\t\t\t\n<div class=\"row row-collapse\"  id=\"row-952906226\">\n\n\t<div id=\"col-55132136\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner dark\" style=\"background-color:rgb(251, 201, 51);\" >\n\t\t\t\n\t\t\t\n<h3>2024<\/h3>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-855147433\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\" style=\"background-color:rgb(255,255,255);\" >\n\t\t\t\n\t\t\t\n<ul>\n<li>Dia Mundial da \u00c1gua - Coopera\u00e7\u00e3o com a Adelholzner Mineral<\/li>\n<li>Desenvolvimento da plataforma de refer\u00eancias \u201cMundo do ecoturbino<\/li>\n<li>In\u00edcio do ecoturbino Pa\u00edses do M\u00e9dio Oriente - P\u00e1gina <a href=\"https:\/\/ecoturbino.me\/\" target=\"_blank\" rel=\"noopener\">ecoturbino M\u00e9dio Oriente<\/a> est\u00e1 online<\/li>\n<li>In\u00edcio da coopera\u00e7\u00e3o com a Miele International<\/li>\n<li><a href=\"https:\/\/ecoturbino.shop\/sustainability-award-gold-for-ecoturbino\/\" target=\"_blank\" rel=\"noopener\">Pr\u00e9mio de Sustentabilidade 2024 em OURO<\/a> para ecoturbino da GARTEN+HAUS na categoria Produtos<\/li>\n<li><a href=\"https:\/\/ecoturbino.shop\/hotel-sustainability-award-2024\/\" target=\"_blank\" rel=\"noopener\">Pr\u00e9mio de Sustentabilidade Hoteleira 2024<\/a> - A ecoturbino recebe um pr\u00e9mio na categoria de Tecnologia Sustent\u00e1vel<\/li>\n<li>Portal <a href=\"https:\/\/ecoturbino.world\/pt\/\" target=\"_blank\" rel=\"noopener\">Mundo do ecoturbino<\/a> | A p\u00e1gina de refer\u00eancias do parceiro est\u00e1 online<\/li>\n<\/ul>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<style>\n#row-952906226 > .col > .col-inner {\n  padding: 10px 20px 2px 20px;\n}\n<\/style>\n<\/div>\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-106673445 > .col-inner {\n  margin: 0px 0px 25px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n<div class=\"row row-collapse align-equal\"  id=\"row-1410880697\">\n\n\t<div id=\"col-241185658\" class=\"col medium-5 small-12 large-5\"  data-animate=\"bounceInUp\">\n\t\t\t\t<div class=\"col-inner box-shadow-2\"  >\n\t\t\t\n\t\t\t\n<div class=\"row row-collapse\"  id=\"row-1866270718\">\n\n\t<div id=\"col-183529701\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner dark\" style=\"background-color:#53a600;\" >\n\t\t\t\n\t\t\t\n<h3>2023<\/h3>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-14243866\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\" style=\"background-color:rgb(255,255,255);\" >\n\t\t\t\n\t\t\t\n<ul>\n<li>Atribui\u00e7\u00e3o do r\u00f3tulo ecol\u00f3gico<\/li>\n<li>Listagem das cooperativas de compras de hot\u00e9is<\/li>\n<li>Nova loja online <a href=\"https:\/\/en.ecoturbino.shop\/\" target=\"_blank\" rel=\"noopener\">www.ecoturbino.shop<\/a> Coopera\u00e7\u00e3o com a Webdeals Shops GmbH<\/li>\n<li>Coopera\u00e7\u00e3o Hansgrohe: Inclus\u00e3o de produtos hansgrohe num conjunto completo, incluindo mangueiras de duche e cabe\u00e7as de chuveiro<\/li>\n<li>17.4.2023 cessa\u00e7\u00e3o da coopera\u00e7\u00e3o com o grupo Rabmer \u00c1ustria<\/li>\n<\/ul>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<style>\n#row-1866270718 > .col > .col-inner {\n  padding: 10px 20px 2px 20px;\n}\n<\/style>\n<\/div>\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-241185658 > .col-inner {\n  margin: 0px 0px 25px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-776846081\" class=\"col medium-2 small-12 large-2 small-col-first\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t<div class=\"is-border is-dashed\"\n\t\tstyle=\"border-color:rgb(228, 228, 228);border-width:0px 2px 0px 0px;margin:60px 50% 0px 0px;\">\n\t<\/div>\n\t\t\t\n\n\t\t<div class=\"icon-box featured-box icon-box-center text-center\"  >\n\t\t\t\t\t<div class=\"icon-box-img has-icon-bg\" style=\"width: 60px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" style=\"border-width:3px;color:rgb(83, 166, 0);\">\n\t\t\t\t\t\t<?xml version=\"1.0\" encoding=\"UTF-8\"?>\n<!-- Generated by IcoMoon.io -->\n<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" version=\"1.1\" width=\"16\" height=\"16\" viewbox=\"0 0 16 16\">\n  <path fill=\"#000000\" d=\"M12.531 3.654c1.923 1.387 2.112 5.737 2.49 7.061l-3.58 1.419c-0.365-2.396-3.45-4.193-3.576-6.841s2.743-3.026 4.666-1.639zM14.707 15.822c-2.858 1.039-3.026-2.806-3.026-2.806l3.72-1.513c0 0 1.734 3.436-0.694 4.319zM0.034 2.985c0.379-2.341 2.675-4.101 4.458-2.14s0.872 5.414 2.308 7.365l-3.534 1.528c-0.669-1.204-3.611-4.413-3.232-6.754zM7.1 13.127c-2.34 1.092-3.544-2.564-3.544-2.564l3.7-1.56c0 0 2.599 2.838-0.156 4.124z\"><\/path>\n<\/svg>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n\t<div id=\"gap-1641544909\" class=\"gap-element clearfix hidden\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1641544909 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n<div class=\"row row-collapse align-equal align-right\"  id=\"row-1994460288\">\n\n\t<div id=\"col-345461654\" class=\"col medium-2 small-12 large-2\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t<div class=\"is-border is-dashed\"\n\t\tstyle=\"border-color:rgb(228, 228, 228);border-width:0px 2px 0px 0px;margin:60px 50% 0px 0px;\">\n\t<\/div>\n\t\t\t\n\n\t\t<div class=\"icon-box featured-box icon-box-center text-center\"  >\n\t\t\t\t\t<div class=\"icon-box-img has-icon-bg\" style=\"width: 60px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" style=\"border-width:3px;color:rgb(53, 57, 96);\">\n\t\t\t\t\t\t<?xml version=\"1.0\" encoding=\"UTF-8\"?>\n<!-- Generated by IcoMoon.io -->\n<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" version=\"1.1\" width=\"16\" height=\"16\" viewbox=\"0 0 16 16\">\n  <path fill=\"#000000\" d=\"M12.531 3.654c1.923 1.387 2.112 5.737 2.49 7.061l-3.58 1.419c-0.365-2.396-3.45-4.193-3.576-6.841s2.743-3.026 4.666-1.639zM14.707 15.822c-2.858 1.039-3.026-2.806-3.026-2.806l3.72-1.513c0 0 1.734 3.436-0.694 4.319zM0.034 2.985c0.379-2.341 2.675-4.101 4.458-2.14s0.872 5.414 2.308 7.365l-3.534 1.528c-0.669-1.204-3.611-4.413-3.232-6.754zM7.1 13.127c-2.34 1.092-3.544-2.564-3.544-2.564l3.7-1.56c0 0 2.599 2.838-0.156 4.124z\"><\/path>\n<\/svg>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n\t<div id=\"gap-318671998\" class=\"gap-element clearfix hidden\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-318671998 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1086817526\" class=\"col medium-5 small-12 large-5\"  data-animate=\"bounceInUp\">\n\t\t\t\t<div class=\"col-inner box-shadow-2\"  >\n\t\t\t\n\t\t\t\n<div class=\"row row-collapse\"  id=\"row-1313890156\">\n\n\t<div id=\"col-542385887\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner dark\" style=\"background-color:rgb(53, 57, 96);\" >\n\t\t\t\n\t\t\t\n<h3>2022<\/h3>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1833570526\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\" style=\"background-color:rgb(255,255,255);\" >\n\t\t\t\n\t\t\t\n<ul>\n<li>Hospital ISAR de Munique equipado com tecnologia ecoturbina<\/li>\n<li>Elevada procura de cabe\u00e7as de chuveiro economizadoras de \u00e1gua - altera\u00e7\u00f5es clim\u00e1ticas<\/li>\n<li>Lan\u00e7amento do produto Ecoturbino s\u00e9rie Deluxe<\/li>\n<\/ul>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<style>\n#row-1313890156 > .col > .col-inner {\n  padding: 10px 20px 2px 20px;\n}\n<\/style>\n<\/div>\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1086817526 > .col-inner {\n  margin: 0px 0px 25px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n<div class=\"row row-collapse align-equal\"  id=\"row-1534284416\">\n\n\t<div id=\"col-149675496\" class=\"col medium-5 small-12 large-5\"  data-animate=\"bounceInUp\">\n\t\t\t\t<div class=\"col-inner box-shadow-2\"  >\n\t\t\t\n\t\t\t\n<div class=\"row row-collapse\"  id=\"row-1703801319\">\n\n\t<div id=\"col-1843419303\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner dark\" style=\"background-color:rgb(0, 139, 153);\" >\n\t\t\t\n\t\t\t\n<h3>2021<\/h3>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1675623255\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\" style=\"background-color:rgb(255,255,255);\" >\n\t\t\t\n\t\t\t\n<ul>\n<li>Inova\u00e7\u00e3o austr\u00edaca poupa \u00e1gua e energia no Dubai<\/li>\n<li>Grupo Johannesbad na Alemanha totalmente equipado com a tecnologia ecoturbino<\/li>\n<li>Optimiza\u00e7\u00f5es cont\u00ednuas do sistema ecoturbiono<\/li>\n<\/ul>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<style>\n#row-1703801319 > .col > .col-inner {\n  padding: 10px 20px 2px 20px;\n}\n<\/style>\n<\/div>\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-149675496 > .col-inner {\n  margin: 0px 0px 25px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-183121715\" class=\"col medium-2 small-12 large-2 small-col-first\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t<div class=\"is-border is-dashed\"\n\t\tstyle=\"border-color:rgb(228, 228, 228);border-width:0px 2px 0px 0px;margin:60px 50% 0px 0px;\">\n\t<\/div>\n\t\t\t\n\n\t\t<div class=\"icon-box featured-box icon-box-center text-center\"  >\n\t\t\t\t\t<div class=\"icon-box-img has-icon-bg\" style=\"width: 60px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" style=\"border-width:3px;color:rgb(0, 139, 153);\">\n\t\t\t\t\t\t<?xml version=\"1.0\" encoding=\"UTF-8\"?>\n<!-- Generated by IcoMoon.io -->\n<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" version=\"1.1\" width=\"16\" height=\"16\" viewbox=\"0 0 16 16\">\n  <path fill=\"#000000\" d=\"M12.531 3.654c1.923 1.387 2.112 5.737 2.49 7.061l-3.58 1.419c-0.365-2.396-3.45-4.193-3.576-6.841s2.743-3.026 4.666-1.639zM14.707 15.822c-2.858 1.039-3.026-2.806-3.026-2.806l3.72-1.513c0 0 1.734 3.436-0.694 4.319zM0.034 2.985c0.379-2.341 2.675-4.101 4.458-2.14s0.872 5.414 2.308 7.365l-3.534 1.528c-0.669-1.204-3.611-4.413-3.232-6.754zM7.1 13.127c-2.34 1.092-3.544-2.564-3.544-2.564l3.7-1.56c0 0 2.599 2.838-0.156 4.124z\"><\/path>\n<\/svg>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n\t<div id=\"gap-435466581\" class=\"gap-element clearfix hidden\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-435466581 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n<div class=\"row row-collapse align-equal align-right\"  id=\"row-1235063645\">\n\n\t<div id=\"col-528329726\" class=\"col medium-2 small-12 large-2\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t<div class=\"is-border is-dashed\"\n\t\tstyle=\"border-color:rgb(228, 228, 228);border-width:0px 2px 0px 0px;margin:60px 50% 0px 0px;\">\n\t<\/div>\n\t\t\t\n\n\t\t<div class=\"icon-box featured-box icon-box-center text-center\"  >\n\t\t\t\t\t<div class=\"icon-box-img has-icon-bg\" style=\"width: 60px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" style=\"border-width:3px;color:rgb(251, 201, 51);\">\n\t\t\t\t\t\t<?xml version=\"1.0\" encoding=\"UTF-8\"?>\n<!-- Generated by IcoMoon.io -->\n<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" version=\"1.1\" width=\"16\" height=\"16\" viewbox=\"0 0 16 16\">\n  <path fill=\"#000000\" d=\"M12.531 3.654c1.923 1.387 2.112 5.737 2.49 7.061l-3.58 1.419c-0.365-2.396-3.45-4.193-3.576-6.841s2.743-3.026 4.666-1.639zM14.707 15.822c-2.858 1.039-3.026-2.806-3.026-2.806l3.72-1.513c0 0 1.734 3.436-0.694 4.319zM0.034 2.985c0.379-2.341 2.675-4.101 4.458-2.14s0.872 5.414 2.308 7.365l-3.534 1.528c-0.669-1.204-3.611-4.413-3.232-6.754zM7.1 13.127c-2.34 1.092-3.544-2.564-3.544-2.564l3.7-1.56c0 0 2.599 2.838-0.156 4.124z\"><\/path>\n<\/svg>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n\t<div id=\"gap-1114922754\" class=\"gap-element clearfix hidden\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1114922754 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-306222036\" class=\"col medium-5 small-12 large-5\"  data-animate=\"bounceInUp\">\n\t\t\t\t<div class=\"col-inner box-shadow-2\"  >\n\t\t\t\n\t\t\t\n<div class=\"row row-collapse\"  id=\"row-1256183733\">\n\n\t<div id=\"col-1744879903\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner dark\" style=\"background-color:rgb(251, 201, 51);\" >\n\t\t\t\n\t\t\t\n<h3>2018<\/h3>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-861451697\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\" style=\"background-color:rgb(255,255,255);\" >\n\t\t\t\n\t\t\t\n<ul>\n<li>SAS Z\u00fcrich, Su\u00ed\u00e7a<\/li>\n<li>Registo internacional da marca ecoturbino\u00ae n.\u00ba 1315887<\/li>\n<\/ul>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<style>\n#row-1256183733 > .col > .col-inner {\n  padding: 10px 20px 2px 20px;\n}\n<\/style>\n<\/div>\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-306222036 > .col-inner {\n  margin: 0px 0px 25px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n<div class=\"row row-collapse align-equal\"  id=\"row-1973112632\">\n\n\t<div id=\"col-2041363768\" class=\"col medium-5 small-12 large-5\"  data-animate=\"bounceInUp\">\n\t\t\t\t<div class=\"col-inner box-shadow-2\"  >\n\t\t\t\n\t\t\t\n<div class=\"row row-collapse\"  id=\"row-296775950\">\n\n\t<div id=\"col-697909572\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner dark\" style=\"background-color:#53a600;\" >\n\t\t\t\n\t\t\t\n<h3>2016<\/h3>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-492809064\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\" style=\"background-color:rgb(255,255,255);\" >\n\t\t\t\n\t\t\t\n<ul>\n<li>2 minutos 2 milh\u00f5es Programa de televis\u00e3o temporada 3 epis\u00f3dio 5<\/li>\n<li>30 000 pe\u00e7as de ecoturbino vendidas a fornecedores de energia como medida de efici\u00eancia energ\u00e9tica eleg\u00edvel<\/li>\n<\/ul>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<style>\n#row-296775950 > .col > .col-inner {\n  padding: 10px 20px 2px 20px;\n}\n<\/style>\n<\/div>\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-2041363768 > .col-inner {\n  margin: 0px 0px 25px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-213554658\" class=\"col medium-2 small-12 large-2 small-col-first\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t<div class=\"is-border is-dashed\"\n\t\tstyle=\"border-color:rgb(228, 228, 228);border-width:0px 2px 0px 0px;margin:60px 50% 0px 0px;\">\n\t<\/div>\n\t\t\t\n\n\t\t<div class=\"icon-box featured-box icon-box-center text-center\"  >\n\t\t\t\t\t<div class=\"icon-box-img has-icon-bg\" style=\"width: 60px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" style=\"border-width:3px;color:rgb(83, 166, 0);\">\n\t\t\t\t\t\t<?xml version=\"1.0\" encoding=\"UTF-8\"?>\n<!-- Generated by IcoMoon.io -->\n<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" version=\"1.1\" width=\"16\" height=\"16\" viewbox=\"0 0 16 16\">\n  <path fill=\"#000000\" d=\"M12.531 3.654c1.923 1.387 2.112 5.737 2.49 7.061l-3.58 1.419c-0.365-2.396-3.45-4.193-3.576-6.841s2.743-3.026 4.666-1.639zM14.707 15.822c-2.858 1.039-3.026-2.806-3.026-2.806l3.72-1.513c0 0 1.734 3.436-0.694 4.319zM0.034 2.985c0.379-2.341 2.675-4.101 4.458-2.14s0.872 5.414 2.308 7.365l-3.534 1.528c-0.669-1.204-3.611-4.413-3.232-6.754zM7.1 13.127c-2.34 1.092-3.544-2.564-3.544-2.564l3.7-1.56c0 0 2.599 2.838-0.156 4.124z\"><\/path>\n<\/svg>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n\t<div id=\"gap-622598313\" class=\"gap-element clearfix hidden\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-622598313 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n<div class=\"row row-collapse align-equal align-right\"  id=\"row-94783633\">\n\n\t<div id=\"col-982924400\" class=\"col medium-2 small-12 large-2\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t<div class=\"is-border is-dashed\"\n\t\tstyle=\"border-color:rgb(228, 228, 228);border-width:0px 2px 0px 0px;margin:60px 50% 0px 0px;\">\n\t<\/div>\n\t\t\t\n\n\t\t<div class=\"icon-box featured-box icon-box-center text-center\"  >\n\t\t\t\t\t<div class=\"icon-box-img has-icon-bg\" style=\"width: 60px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" style=\"border-width:3px;color:rgb(53, 57, 96);\">\n\t\t\t\t\t\t<?xml version=\"1.0\" encoding=\"UTF-8\"?>\n<!-- Generated by IcoMoon.io -->\n<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" version=\"1.1\" width=\"16\" height=\"16\" viewbox=\"0 0 16 16\">\n  <path fill=\"#000000\" d=\"M12.531 3.654c1.923 1.387 2.112 5.737 2.49 7.061l-3.58 1.419c-0.365-2.396-3.45-4.193-3.576-6.841s2.743-3.026 4.666-1.639zM14.707 15.822c-2.858 1.039-3.026-2.806-3.026-2.806l3.72-1.513c0 0 1.734 3.436-0.694 4.319zM0.034 2.985c0.379-2.341 2.675-4.101 4.458-2.14s0.872 5.414 2.308 7.365l-3.534 1.528c-0.669-1.204-3.611-4.413-3.232-6.754zM7.1 13.127c-2.34 1.092-3.544-2.564-3.544-2.564l3.7-1.56c0 0 2.599 2.838-0.156 4.124z\"><\/path>\n<\/svg>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n\t<div id=\"gap-976515590\" class=\"gap-element clearfix hidden\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-976515590 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-38664591\" class=\"col medium-5 small-12 large-5\"  data-animate=\"bounceInUp\">\n\t\t\t\t<div class=\"col-inner box-shadow-2\"  >\n\t\t\t\n\t\t\t\n<div class=\"row row-collapse\"  id=\"row-1625356077\">\n\n\t<div id=\"col-1423940675\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner dark\" style=\"background-color:rgb(53, 57, 96);\" >\n\t\t\t\n\t\t\t\n<h3>2015<\/h3>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1801191114\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\" style=\"background-color:rgb(255,255,255);\" >\n\t\t\t\n\t\t\t\n<ul>\n<li>Pedido de registo da marca ecoturbino - Altera\u00e7\u00e3o da designa\u00e7\u00e3o da marca<\/li>\n<li>Especializa\u00e7\u00e3o SV Kren<\/li>\n<li>Certifica\u00e7\u00e3o T\u00dcV do ecoturbino como medida de efici\u00eancia energ\u00e9tica<\/li>\n<li>agosto: In\u00edcio da parceria de vendas com o Rabmer Group Austria<\/li>\n<\/ul>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<style>\n#row-1625356077 > .col > .col-inner {\n  padding: 10px 20px 2px 20px;\n}\n<\/style>\n<\/div>\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-38664591 > .col-inner {\n  margin: 0px 0px 25px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n<div class=\"row row-collapse align-equal\"  id=\"row-154634624\">\n\n\t<div id=\"col-1118651951\" class=\"col medium-5 small-12 large-5\"  data-animate=\"bounceInUp\">\n\t\t\t\t<div class=\"col-inner box-shadow-2\"  >\n\t\t\t\n\t\t\t\n<div class=\"row row-collapse\"  id=\"row-1914208409\">\n\n\t<div id=\"col-1348592444\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner dark\" style=\"background-color:rgb(0, 139, 153);\" >\n\t\t\t\n\t\t\t\n<h3>2008<\/h3>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1857566695\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\" style=\"background-color:rgb(255,255,255);\" >\n\t\t\t\n\t\t\t\n<ul>\n<li>Iniciar a distribui\u00e7\u00e3o a n\u00edvel europeu como redutor de \u00e1gua<\/li>\n<\/ul>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<style>\n#row-1914208409 > .col > .col-inner {\n  padding: 10px 20px 2px 20px;\n}\n<\/style>\n<\/div>\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-1118651951 > .col-inner {\n  margin: 0px 0px 25px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-216453908\" class=\"col medium-2 small-12 large-2 small-col-first\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t<div class=\"is-border is-dashed\"\n\t\tstyle=\"border-color:rgb(228, 228, 228);border-width:0px 2px 0px 0px;margin:60px 50% 0px 0px;\">\n\t<\/div>\n\t\t\t\n\n\t\t<div class=\"icon-box featured-box icon-box-center text-center\"  >\n\t\t\t\t\t<div class=\"icon-box-img has-icon-bg\" style=\"width: 60px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" style=\"border-width:3px;color:rgb(0, 139, 153);\">\n\t\t\t\t\t\t<?xml version=\"1.0\" encoding=\"UTF-8\"?>\n<!-- Generated by IcoMoon.io -->\n<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" version=\"1.1\" width=\"16\" height=\"16\" viewbox=\"0 0 16 16\">\n  <path fill=\"#000000\" d=\"M12.531 3.654c1.923 1.387 2.112 5.737 2.49 7.061l-3.58 1.419c-0.365-2.396-3.45-4.193-3.576-6.841s2.743-3.026 4.666-1.639zM14.707 15.822c-2.858 1.039-3.026-2.806-3.026-2.806l3.72-1.513c0 0 1.734 3.436-0.694 4.319zM0.034 2.985c0.379-2.341 2.675-4.101 4.458-2.14s0.872 5.414 2.308 7.365l-3.534 1.528c-0.669-1.204-3.611-4.413-3.232-6.754zM7.1 13.127c-2.34 1.092-3.544-2.564-3.544-2.564l3.7-1.56c0 0 2.599 2.838-0.156 4.124z\"><\/path>\n<\/svg>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n\t<div id=\"gap-1925045750\" class=\"gap-element clearfix hidden\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-1925045750 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n<div class=\"row row-collapse align-equal align-right\"  id=\"row-1763537775\">\n\n\t<div id=\"col-981384041\" class=\"col medium-2 small-12 large-2\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t<div class=\"is-border is-dashed\"\n\t\tstyle=\"border-color:rgb(228, 228, 228);border-width:0px 2px 0px 0px;margin:60px 50% 0px 0px;\">\n\t<\/div>\n\t\t\t\n\n\t\t<div class=\"icon-box featured-box icon-box-center text-center\"  >\n\t\t\t\t\t<div class=\"icon-box-img has-icon-bg\" style=\"width: 60px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" style=\"border-width:3px;color:rgb(251, 201, 51);\">\n\t\t\t\t\t\t<?xml version=\"1.0\" encoding=\"UTF-8\"?>\n<!-- Generated by IcoMoon.io -->\n<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" version=\"1.1\" width=\"16\" height=\"16\" viewbox=\"0 0 16 16\">\n  <path fill=\"#000000\" d=\"M12.531 3.654c1.923 1.387 2.112 5.737 2.49 7.061l-3.58 1.419c-0.365-2.396-3.45-4.193-3.576-6.841s2.743-3.026 4.666-1.639zM14.707 15.822c-2.858 1.039-3.026-2.806-3.026-2.806l3.72-1.513c0 0 1.734 3.436-0.694 4.319zM0.034 2.985c0.379-2.341 2.675-4.101 4.458-2.14s0.872 5.414 2.308 7.365l-3.534 1.528c-0.669-1.204-3.611-4.413-3.232-6.754zM7.1 13.127c-2.34 1.092-3.544-2.564-3.544-2.564l3.7-1.56c0 0 2.599 2.838-0.156 4.124z\"><\/path>\n<\/svg>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n\t<div id=\"gap-506507386\" class=\"gap-element clearfix hidden\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-506507386 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-2003501290\" class=\"col medium-5 small-12 large-5\"  data-animate=\"bounceInUp\">\n\t\t\t\t<div class=\"col-inner box-shadow-2\"  >\n\t\t\t\n\t\t\t\n<div class=\"row row-collapse\"  id=\"row-401746677\">\n\n\t<div id=\"col-978995359\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner dark\" style=\"background-color:rgb(251, 201, 51);\" >\n\t\t\t\n\t\t\t\n<h3>2007<\/h3>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-801465502\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\" style=\"background-color:rgb(255,255,255);\" >\n\t\t\t\n\t\t\t\n<ul>\n<li>Prepara\u00e7\u00e3o da produ\u00e7\u00e3o e confirma\u00e7\u00e3o do pedido de patente<\/li>\n<li>Primeira refer\u00eancia SAS Hotel Vienna via newsletter<\/li>\n<\/ul>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<style>\n#row-401746677 > .col > .col-inner {\n  padding: 10px 20px 2px 20px;\n}\n<\/style>\n<\/div>\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-2003501290 > .col-inner {\n  margin: 0px 0px 25px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n<\/div>\n<div class=\"row row-collapse align-equal\"  id=\"row-2070551256\">\n\n\t<div id=\"col-996067528\" class=\"col medium-5 small-12 large-5\"  data-animate=\"bounceInUp\">\n\t\t\t\t<div class=\"col-inner box-shadow-2\"  >\n\t\t\t\n\t\t\t\n<div class=\"row row-collapse\"  id=\"row-1593645562\">\n\n\t<div id=\"col-1477137874\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner dark\" style=\"background-color:#53a600;\" >\n\t\t\t\n\t\t\t\n<h3>2004<\/h3>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-2003900753\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\" style=\"background-color:rgb(255,255,255);\" >\n\t\t\t\n\t\t\t\n<ul>\n<li>Considera\u00e7\u00f5es iniciais e ideia do princ\u00edpio funcional<\/li>\n<\/ul>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<style>\n#row-1593645562 > .col > .col-inner {\n  padding: 10px 20px 2px 20px;\n}\n<\/style>\n<\/div>\n\t\t<\/div>\n\t\t\t\t\n<style>\n#col-996067528 > .col-inner {\n  margin: 0px 0px 25px 0px;\n}\n<\/style>\n\t<\/div>\n\n\t\n\n\t<div id=\"col-2068008416\" class=\"col medium-2 small-12 large-2 small-col-first\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t<div class=\"is-border is-dashed\"\n\t\tstyle=\"border-color:rgb(228, 228, 228);border-width:0px 2px 0px 0px;margin:60px 50% 0px 0px;\">\n\t<\/div>\n\t\t\t\n\n\t\t<div class=\"icon-box featured-box icon-box-center text-center\"  >\n\t\t\t\t\t<div class=\"icon-box-img has-icon-bg\" style=\"width: 60px\">\n\t\t\t\t<div class=\"icon\">\n\t\t\t\t\t<div class=\"icon-inner\" style=\"border-width:3px;color:rgb(83, 166, 0);\">\n\t\t\t\t\t\t<?xml version=\"1.0\" encoding=\"UTF-8\"?>\n<!-- Generated by IcoMoon.io -->\n<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" version=\"1.1\" width=\"16\" height=\"16\" viewbox=\"0 0 16 16\">\n  <path fill=\"#000000\" d=\"M12.531 3.654c1.923 1.387 2.112 5.737 2.49 7.061l-3.58 1.419c-0.365-2.396-3.45-4.193-3.576-6.841s2.743-3.026 4.666-1.639zM14.707 15.822c-2.858 1.039-3.026-2.806-3.026-2.806l3.72-1.513c0 0 1.734 3.436-0.694 4.319zM0.034 2.985c0.379-2.341 2.675-4.101 4.458-2.14s0.872 5.414 2.308 7.365l-3.534 1.528c-0.669-1.204-3.611-4.413-3.232-6.754zM7.1 13.127c-2.34 1.092-3.544-2.564-3.544-2.564l3.7-1.56c0 0 2.599 2.838-0.156 4.124z\"><\/path>\n<\/svg>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t<div class=\"icon-box-text last-reset\">\n\t\t\t\t\t\t\t\t\t\n\t<div id=\"gap-2030930191\" class=\"gap-element clearfix hidden\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-2030930191 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n\t\t<\/div>\n\t<\/div>\n\t\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_83093802 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n<div class=\"row\"  id=\"row-1216244826\">\n\n\t<div id=\"col-649737386\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n<div class=\"is-divider divider clearfix\" style=\"max-width:100%;height:1px;\"><\/div>\n<h3>Excerto dos nossos parceiros ecoturbino\u00ae e refer\u00eancias que poupam \u00e1gua de forma sustent\u00e1vel<\/h3>\n\n  \n    <div id=\"gallery-1459233455\" class=\"row large-columns-5 medium-columns-3 small-columns-2 row-masonry\" data-packery-options='{\"itemSelector\": \".col\", \"gutter\": 0, \"presentageWidth\" : true}'>\n\n  <div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n                        <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/ecoturbino.world\/wp-content\/uploads\/2023\/12\/marriott-hotels-logo.svg\" class=\"attachment-medium size-medium\" alt=\"Log\u00f3tipo dos hot\u00e9is Marriott\" ids=\"1041,1036,1037,891,946,947,223,1373,1370,1367,1365,1362,1360,1359,1357,1355,1351,1349,1348,1347,1346,1342,1340,1330,1327,1274,1272,1267,1263,1253,1251,1250,1236,1234,1232,1230,1181,1167,1158,1067,966,965,964,962,961,960,959,958,957,955,953,952,950,949,948,935,934,933,932,919,918,916,915,914,913,911,904,897,894,892,874,871,868,867,865,864,843,828\" style=\"none\" lightbox=\"false\" type=\"masonry\" columns=\"5\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p>Log\u00f3tipo dos hot\u00e9is Marriott<\/p>\n              <\/div>\n            <\/div>\n                      <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n                        <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/ecoturbino.world\/wp-content\/uploads\/2023\/12\/johannesbad-hotels-logo.svg\" class=\"attachment-medium size-medium\" alt=\"Log\u00f3tipo dos Hot\u00e9is Johannesbad\" ids=\"1041,1036,1037,891,946,947,223,1373,1370,1367,1365,1362,1360,1359,1357,1355,1351,1349,1348,1347,1346,1342,1340,1330,1327,1274,1272,1267,1263,1253,1251,1250,1236,1234,1232,1230,1181,1167,1158,1067,966,965,964,962,961,960,959,958,957,955,953,952,950,949,948,935,934,933,932,919,918,916,915,914,913,911,904,897,894,892,874,871,868,867,865,864,843,828\" style=\"none\" lightbox=\"false\" type=\"masonry\" columns=\"5\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p>Log\u00f3tipo dos Hot\u00e9is Johannesbad<\/p>\n              <\/div>\n            <\/div>\n                      <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n                        <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/ecoturbino.world\/wp-content\/uploads\/2023\/12\/johannesbad-medizin-logo.svg\" class=\"attachment-medium size-medium\" alt=\"Logotipo da Johannesbad Medizin\" ids=\"1041,1036,1037,891,946,947,223,1373,1370,1367,1365,1362,1360,1359,1357,1355,1351,1349,1348,1347,1346,1342,1340,1330,1327,1274,1272,1267,1263,1253,1251,1250,1236,1234,1232,1230,1181,1167,1158,1067,966,965,964,962,961,960,959,958,957,955,953,952,950,949,948,935,934,933,932,919,918,916,915,914,913,911,904,897,894,892,874,871,868,867,865,864,843,828\" style=\"none\" lightbox=\"false\" type=\"masonry\" columns=\"5\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p>Logotipo da Johannesbad Medizin<\/p>\n              <\/div>\n            <\/div>\n                      <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n                        <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/ecoturbino.world\/wp-content\/uploads\/2023\/12\/danway-logo.svg\" class=\"attachment-medium size-medium\" alt=\"Log\u00f3tipo da Danway Emirates LLC\" ids=\"1041,1036,1037,891,946,947,223,1373,1370,1367,1365,1362,1360,1359,1357,1355,1351,1349,1348,1347,1346,1342,1340,1330,1327,1274,1272,1267,1263,1253,1251,1250,1236,1234,1232,1230,1181,1167,1158,1067,966,965,964,962,961,960,959,958,957,955,953,952,950,949,948,935,934,933,932,919,918,916,915,914,913,911,904,897,894,892,874,871,868,867,865,864,843,828\" style=\"none\" lightbox=\"false\" type=\"masonry\" columns=\"5\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p>Log\u00f3tipo da Danway Emirates LLC<\/p>\n              <\/div>\n            <\/div>\n                      <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n                        <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/ecoturbino.world\/wp-content\/uploads\/2023\/12\/pichlarn-schloss-hotel-logo.svg\" class=\"attachment-medium size-medium\" alt=\"Log\u00f3tipo do Imlauer Hotel Schloss Pichlarn\" ids=\"1041,1036,1037,891,946,947,223,1373,1370,1367,1365,1362,1360,1359,1357,1355,1351,1349,1348,1347,1346,1342,1340,1330,1327,1274,1272,1267,1263,1253,1251,1250,1236,1234,1232,1230,1181,1167,1158,1067,966,965,964,962,961,960,959,958,957,955,953,952,950,949,948,935,934,933,932,919,918,916,915,914,913,911,904,897,894,892,874,871,868,867,865,864,843,828\" style=\"none\" lightbox=\"false\" type=\"masonry\" columns=\"5\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p>Log\u00f3tipo do Imlauer Hotel Schloss Pichlarn<\/p>\n              <\/div>\n            <\/div>\n                      <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n                        <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/ecoturbino.world\/wp-content\/uploads\/2023\/12\/alpina-hotel-logo.svg\" class=\"attachment-medium size-medium\" alt=\"Log\u00f3tipo do Marco Polo Alpina Familien- &amp; Sporthotel\" ids=\"1041,1036,1037,891,946,947,223,1373,1370,1367,1365,1362,1360,1359,1357,1355,1351,1349,1348,1347,1346,1342,1340,1330,1327,1274,1272,1267,1263,1253,1251,1250,1236,1234,1232,1230,1181,1167,1158,1067,966,965,964,962,961,960,959,958,957,955,953,952,950,949,948,935,934,933,932,919,918,916,915,914,913,911,904,897,894,892,874,871,868,867,865,864,843,828\" style=\"none\" lightbox=\"false\" type=\"masonry\" columns=\"5\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p>Log\u00f3tipo do Marco Polo Alpina Familien- &amp; Sporthotel<\/p>\n              <\/div>\n            <\/div>\n                      <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n                        <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img decoding=\"async\" width=\"1000\" height=\"246\" src=\"https:\/\/ecoturbino.world\/wp-content\/uploads\/2023\/12\/Miele_logo.svg\" class=\"attachment-medium size-medium\" alt=\"Log\u00f3tipo Miele\" ids=\"1041,1036,1037,891,946,947,223,1373,1370,1367,1365,1362,1360,1359,1357,1355,1351,1349,1348,1347,1346,1342,1340,1330,1327,1274,1272,1267,1263,1253,1251,1250,1236,1234,1232,1230,1181,1167,1158,1067,966,965,964,962,961,960,959,958,957,955,953,952,950,949,948,935,934,933,932,919,918,916,915,914,913,911,904,897,894,892,874,871,868,867,865,864,843,828\" style=\"none\" lightbox=\"false\" type=\"masonry\" columns=\"5\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p>Log\u00f3tipo Miele<\/p>\n              <\/div>\n            <\/div>\n                      <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n                        <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img decoding=\"async\" width=\"275\" height=\"205\" src=\"https:\/\/ecoturbino.world\/wp-content\/uploads\/2023\/12\/simon-hotel-logo.webp\" class=\"attachment-medium size-medium\" alt=\"Logotipo do Simon Hotel Cafe\" ids=\"1041,1036,1037,891,946,947,223,1373,1370,1367,1365,1362,1360,1359,1357,1355,1351,1349,1348,1347,1346,1342,1340,1330,1327,1274,1272,1267,1263,1253,1251,1250,1236,1234,1232,1230,1181,1167,1158,1067,966,965,964,962,961,960,959,958,957,955,953,952,950,949,948,935,934,933,932,919,918,916,915,914,913,911,904,897,894,892,874,871,868,867,865,864,843,828\" style=\"none\" lightbox=\"false\" type=\"masonry\" columns=\"5\" srcset=\"https:\/\/ecoturbino.world\/wp-content\/uploads\/2023\/12\/simon-hotel-logo.webp 275w, https:\/\/ecoturbino.world\/wp-content\/uploads\/2023\/12\/simon-hotel-logo-240x180.webp 240w\" sizes=\"(max-width: 275px) 100vw, 275px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p>Logotipo do Simon Hotel Cafe<\/p>\n              <\/div>\n            <\/div>\n                      <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n                        <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/ecoturbino.world\/wp-content\/uploads\/2023\/12\/gaestehaus-haiminger-logo.svg\" class=\"attachment-medium size-medium\" alt=\"G\u00e4stehaus Haiminger (vormals G\u00e4stehaus Schmelz) Log\u00f3tipo\" ids=\"1041,1036,1037,891,946,947,223,1373,1370,1367,1365,1362,1360,1359,1357,1355,1351,1349,1348,1347,1346,1342,1340,1330,1327,1274,1272,1267,1263,1253,1251,1250,1236,1234,1232,1230,1181,1167,1158,1067,966,965,964,962,961,960,959,958,957,955,953,952,950,949,948,935,934,933,932,919,918,916,915,914,913,911,904,897,894,892,874,871,868,867,865,864,843,828\" style=\"none\" lightbox=\"false\" type=\"masonry\" columns=\"5\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p>G\u00e4stehaus Haiminger (vormals G\u00e4stehaus Schmelz) Log\u00f3tipo<\/p>\n              <\/div>\n            <\/div>\n                      <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n                        <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img decoding=\"async\" width=\"1000\" height=\"552\" src=\"https:\/\/ecoturbino.world\/wp-content\/uploads\/2023\/12\/hotel-schachner-logo.svg\" class=\"attachment-medium size-medium\" alt=\"Log\u00f3tipo do Hotel Schachner\" ids=\"1041,1036,1037,891,946,947,223,1373,1370,1367,1365,1362,1360,1359,1357,1355,1351,1349,1348,1347,1346,1342,1340,1330,1327,1274,1272,1267,1263,1253,1251,1250,1236,1234,1232,1230,1181,1167,1158,1067,966,965,964,962,961,960,959,958,957,955,953,952,950,949,948,935,934,933,932,919,918,916,915,914,913,911,904,897,894,892,874,871,868,867,865,864,843,828\" style=\"none\" lightbox=\"false\" type=\"masonry\" columns=\"5\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p>Log\u00f3tipo do Hotel Schachner<\/p>\n              <\/div>\n            <\/div>\n                      <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n                        <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/ecoturbino.world\/wp-content\/uploads\/2023\/12\/sacher-baden-logo.svg\" class=\"attachment-medium size-medium\" alt=\"Log\u00f3tipo Sacher Baden bei Wien\" ids=\"1041,1036,1037,891,946,947,223,1373,1370,1367,1365,1362,1360,1359,1357,1355,1351,1349,1348,1347,1346,1342,1340,1330,1327,1274,1272,1267,1263,1253,1251,1250,1236,1234,1232,1230,1181,1167,1158,1067,966,965,964,962,961,960,959,958,957,955,953,952,950,949,948,935,934,933,932,919,918,916,915,914,913,911,904,897,894,892,874,871,868,867,865,864,843,828\" style=\"none\" lightbox=\"false\" type=\"masonry\" columns=\"5\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p>Log\u00f3tipo Sacher Baden bei Wien<\/p>\n              <\/div>\n            <\/div>\n                      <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n                        <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/ecoturbino.world\/wp-content\/uploads\/2023\/12\/kirchenwirt-wachau-logo.svg\" class=\"attachment-medium size-medium\" alt=\"Logotipo da Kirchenwirt Wei\u00dfenkirchen\" ids=\"1041,1036,1037,891,946,947,223,1373,1370,1367,1365,1362,1360,1359,1357,1355,1351,1349,1348,1347,1346,1342,1340,1330,1327,1274,1272,1267,1263,1253,1251,1250,1236,1234,1232,1230,1181,1167,1158,1067,966,965,964,962,961,960,959,958,957,955,953,952,950,949,948,935,934,933,932,919,918,916,915,914,913,911,904,897,894,892,874,871,868,867,865,864,843,828\" style=\"none\" lightbox=\"false\" type=\"masonry\" columns=\"5\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p>Logotipo da Kirchenwirt Wei\u00dfenkirchen<\/p>\n              <\/div>\n            <\/div>\n                      <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n                        <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/ecoturbino.world\/wp-content\/uploads\/2023\/12\/badclevers-logo.svg\" class=\"attachment-medium size-medium\" alt=\"Log\u00f3tipo do Bad Clevers Gesundheitsresort &amp; SPA\" ids=\"1041,1036,1037,891,946,947,223,1373,1370,1367,1365,1362,1360,1359,1357,1355,1351,1349,1348,1347,1346,1342,1340,1330,1327,1274,1272,1267,1263,1253,1251,1250,1236,1234,1232,1230,1181,1167,1158,1067,966,965,964,962,961,960,959,958,957,955,953,952,950,949,948,935,934,933,932,919,918,916,915,914,913,911,904,897,894,892,874,871,868,867,865,864,843,828\" style=\"none\" lightbox=\"false\" type=\"masonry\" columns=\"5\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p>Log\u00f3tipo do Bad Clevers Gesundheitsresort &amp; SPA<\/p>\n              <\/div>\n            <\/div>\n                      <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n                        <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/ecoturbino.world\/wp-content\/uploads\/2023\/12\/toalstock-hotel-logo.svg\" class=\"attachment-medium size-medium\" alt=\"Log\u00f3tipo do Hotel Toalstock\" ids=\"1041,1036,1037,891,946,947,223,1373,1370,1367,1365,1362,1360,1359,1357,1355,1351,1349,1348,1347,1346,1342,1340,1330,1327,1274,1272,1267,1263,1253,1251,1250,1236,1234,1232,1230,1181,1167,1158,1067,966,965,964,962,961,960,959,958,957,955,953,952,950,949,948,935,934,933,932,919,918,916,915,914,913,911,904,897,894,892,874,871,868,867,865,864,843,828\" style=\"none\" lightbox=\"false\" type=\"masonry\" columns=\"5\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p>Log\u00f3tipo do Hotel Toalstock<\/p>\n              <\/div>\n            <\/div>\n                      <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n                        <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img decoding=\"async\" width=\"275\" height=\"205\" src=\"https:\/\/ecoturbino.world\/wp-content\/uploads\/2023\/12\/probst-privathotel-logo.webp\" class=\"attachment-medium size-medium\" alt=\"Probst Privathotel Log\u00f3tipo\" ids=\"1041,1036,1037,891,946,947,223,1373,1370,1367,1365,1362,1360,1359,1357,1355,1351,1349,1348,1347,1346,1342,1340,1330,1327,1274,1272,1267,1263,1253,1251,1250,1236,1234,1232,1230,1181,1167,1158,1067,966,965,964,962,961,960,959,958,957,955,953,952,950,949,948,935,934,933,932,919,918,916,915,914,913,911,904,897,894,892,874,871,868,867,865,864,843,828\" style=\"none\" lightbox=\"false\" type=\"masonry\" columns=\"5\" srcset=\"https:\/\/ecoturbino.world\/wp-content\/uploads\/2023\/12\/probst-privathotel-logo.webp 275w, https:\/\/ecoturbino.world\/wp-content\/uploads\/2023\/12\/probst-privathotel-logo-240x180.webp 240w\" sizes=\"(max-width: 275px) 100vw, 275px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p>Probst Privathotel Log\u00f3tipo<\/p>\n              <\/div>\n            <\/div>\n                      <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n                        <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/ecoturbino.world\/wp-content\/uploads\/2023\/12\/mewa-textil-logo.svg\" class=\"attachment-medium size-medium\" alt=\"Log\u00f3tipo da MEWA Textil Service\" ids=\"1041,1036,1037,891,946,947,223,1373,1370,1367,1365,1362,1360,1359,1357,1355,1351,1349,1348,1347,1346,1342,1340,1330,1327,1274,1272,1267,1263,1253,1251,1250,1236,1234,1232,1230,1181,1167,1158,1067,966,965,964,962,961,960,959,958,957,955,953,952,950,949,948,935,934,933,932,919,918,916,915,914,913,911,904,897,894,892,874,871,868,867,865,864,843,828\" style=\"none\" lightbox=\"false\" type=\"masonry\" columns=\"5\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p>Log\u00f3tipo da MEWA Textil Service<\/p>\n              <\/div>\n            <\/div>\n                      <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n                        <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/ecoturbino.world\/wp-content\/uploads\/2023\/12\/Logo-Laupheiemer-3S-superior.svg\" class=\"attachment-medium size-medium\" alt=\"Log\u00f3tipo do Hotel Laupheimer Braugasthof\" ids=\"1041,1036,1037,891,946,947,223,1373,1370,1367,1365,1362,1360,1359,1357,1355,1351,1349,1348,1347,1346,1342,1340,1330,1327,1274,1272,1267,1263,1253,1251,1250,1236,1234,1232,1230,1181,1167,1158,1067,966,965,964,962,961,960,959,958,957,955,953,952,950,949,948,935,934,933,932,919,918,916,915,914,913,911,904,897,894,892,874,871,868,867,865,864,843,828\" style=\"none\" lightbox=\"false\" type=\"masonry\" columns=\"5\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p>Log\u00f3tipo do Hotel Laupheimer Braugasthof<\/p>\n              <\/div>\n            <\/div>\n                      <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n                        <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/ecoturbino.world\/wp-content\/uploads\/2023\/12\/bichlerhof-logo.svg\" class=\"attachment-medium size-medium\" alt=\"Log\u00f3tipo Bichlerhof Herz\" ids=\"1041,1036,1037,891,946,947,223,1373,1370,1367,1365,1362,1360,1359,1357,1355,1351,1349,1348,1347,1346,1342,1340,1330,1327,1274,1272,1267,1263,1253,1251,1250,1236,1234,1232,1230,1181,1167,1158,1067,966,965,964,962,961,960,959,958,957,955,953,952,950,949,948,935,934,933,932,919,918,916,915,914,913,911,904,897,894,892,874,871,868,867,865,864,843,828\" style=\"none\" lightbox=\"false\" type=\"masonry\" columns=\"5\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p>Log\u00f3tipo Bichlerhof Herz<\/p>\n              <\/div>\n            <\/div>\n                      <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n                        <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/ecoturbino.world\/wp-content\/uploads\/2023\/12\/logo_turmleiben.svg\" class=\"attachment-medium size-medium\" alt=\"Log\u00f3tipo dos Apartamentos Der TURM LEIBEN\" ids=\"1041,1036,1037,891,946,947,223,1373,1370,1367,1365,1362,1360,1359,1357,1355,1351,1349,1348,1347,1346,1342,1340,1330,1327,1274,1272,1267,1263,1253,1251,1250,1236,1234,1232,1230,1181,1167,1158,1067,966,965,964,962,961,960,959,958,957,955,953,952,950,949,948,935,934,933,932,919,918,916,915,914,913,911,904,897,894,892,874,871,868,867,865,864,843,828\" style=\"none\" lightbox=\"false\" type=\"masonry\" columns=\"5\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p>Log\u00f3tipo dos Apartamentos Der TURM LEIBEN<\/p>\n              <\/div>\n            <\/div>\n                      <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n                        <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/ecoturbino.world\/wp-content\/uploads\/2023\/12\/eichingerbauer-logo.svg\" class=\"attachment-medium size-medium\" alt=\"Log\u00f3tipo do Eichingerbauer Hotel Mondsee\" ids=\"1041,1036,1037,891,946,947,223,1373,1370,1367,1365,1362,1360,1359,1357,1355,1351,1349,1348,1347,1346,1342,1340,1330,1327,1274,1272,1267,1263,1253,1251,1250,1236,1234,1232,1230,1181,1167,1158,1067,966,965,964,962,961,960,959,958,957,955,953,952,950,949,948,935,934,933,932,919,918,916,915,914,913,911,904,897,894,892,874,871,868,867,865,864,843,828\" style=\"none\" lightbox=\"false\" type=\"masonry\" columns=\"5\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p>Log\u00f3tipo do Eichingerbauer Hotel Mondsee<\/p>\n              <\/div>\n            <\/div>\n                      <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n                        <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/ecoturbino.world\/wp-content\/uploads\/2023\/12\/restaurant-freiwild-logo.svg\" class=\"attachment-medium size-medium\" alt=\"Log\u00f3tipo do restaurante Freiwild\" ids=\"1041,1036,1037,891,946,947,223,1373,1370,1367,1365,1362,1360,1359,1357,1355,1351,1349,1348,1347,1346,1342,1340,1330,1327,1274,1272,1267,1263,1253,1251,1250,1236,1234,1232,1230,1181,1167,1158,1067,966,965,964,962,961,960,959,958,957,955,953,952,950,949,948,935,934,933,932,919,918,916,915,914,913,911,904,897,894,892,874,871,868,867,865,864,843,828\" style=\"none\" lightbox=\"false\" type=\"masonry\" columns=\"5\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p>Log\u00f3tipo do restaurante Freiwild<\/p>\n              <\/div>\n            <\/div>\n                      <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n                        <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img decoding=\"async\" width=\"297\" height=\"105\" src=\"https:\/\/ecoturbino.world\/wp-content\/uploads\/2023\/12\/logo_362_1248.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"1041,1036,1037,891,946,947,223,1373,1370,1367,1365,1362,1360,1359,1357,1355,1351,1349,1348,1347,1346,1342,1340,1330,1327,1274,1272,1267,1263,1253,1251,1250,1236,1234,1232,1230,1181,1167,1158,1067,966,965,964,962,961,960,959,958,957,955,953,952,950,949,948,935,934,933,932,919,918,916,915,914,913,911,904,897,894,892,874,871,868,867,865,864,843,828\" style=\"none\" lightbox=\"false\" type=\"masonry\" columns=\"5\" srcset=\"https:\/\/ecoturbino.world\/wp-content\/uploads\/2023\/12\/logo_362_1248.jpg 297w, https:\/\/ecoturbino.world\/wp-content\/uploads\/2023\/12\/logo_362_1248-240x85.jpg 240w\" sizes=\"(max-width: 297px) 100vw, 297px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n                      <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n                        <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img decoding=\"async\" width=\"274\" height=\"121\" src=\"https:\/\/ecoturbino.world\/wp-content\/uploads\/2023\/12\/Holzlodge-logo.png\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"1041,1036,1037,891,946,947,223,1373,1370,1367,1365,1362,1360,1359,1357,1355,1351,1349,1348,1347,1346,1342,1340,1330,1327,1274,1272,1267,1263,1253,1251,1250,1236,1234,1232,1230,1181,1167,1158,1067,966,965,964,962,961,960,959,958,957,955,953,952,950,949,948,935,934,933,932,919,918,916,915,914,913,911,904,897,894,892,874,871,868,867,865,864,843,828\" style=\"none\" lightbox=\"false\" type=\"masonry\" columns=\"5\" srcset=\"https:\/\/ecoturbino.world\/wp-content\/uploads\/2023\/12\/Holzlodge-logo.png 274w, https:\/\/ecoturbino.world\/wp-content\/uploads\/2023\/12\/Holzlodge-logo-240x106.png 240w\" sizes=\"(max-width: 274px) 100vw, 274px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n                      <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n                        <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img decoding=\"async\" width=\"179\" height=\"118\" src=\"https:\/\/ecoturbino.world\/wp-content\/uploads\/2023\/12\/Logo-Radkersburg.png\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"1041,1036,1037,891,946,947,223,1373,1370,1367,1365,1362,1360,1359,1357,1355,1351,1349,1348,1347,1346,1342,1340,1330,1327,1274,1272,1267,1263,1253,1251,1250,1236,1234,1232,1230,1181,1167,1158,1067,966,965,964,962,961,960,959,958,957,955,953,952,950,949,948,935,934,933,932,919,918,916,915,914,913,911,904,897,894,892,874,871,868,867,865,864,843,828\" style=\"none\" lightbox=\"false\" type=\"masonry\" columns=\"5\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n                      <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n                        <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img decoding=\"async\" width=\"1000\" height=\"262\" src=\"https:\/\/ecoturbino.world\/wp-content\/uploads\/2023\/12\/Logo-Gasthof-gross-1000x262.png\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"1041,1036,1037,891,946,947,223,1373,1370,1367,1365,1362,1360,1359,1357,1355,1351,1349,1348,1347,1346,1342,1340,1330,1327,1274,1272,1267,1263,1253,1251,1250,1236,1234,1232,1230,1181,1167,1158,1067,966,965,964,962,961,960,959,958,957,955,953,952,950,949,948,935,934,933,932,919,918,916,915,914,913,911,904,897,894,892,874,871,868,867,865,864,843,828\" style=\"none\" lightbox=\"false\" type=\"masonry\" columns=\"5\" srcset=\"https:\/\/ecoturbino.world\/wp-content\/uploads\/2023\/12\/Logo-Gasthof-gross-1000x262.png 1000w, https:\/\/ecoturbino.world\/wp-content\/uploads\/2023\/12\/Logo-Gasthof-gross-1500x393.png 1500w, https:\/\/ecoturbino.world\/wp-content\/uploads\/2023\/12\/Logo-Gasthof-gross-768x201.png 768w, https:\/\/ecoturbino.world\/wp-content\/uploads\/2023\/12\/Logo-Gasthof-gross-1536x402.png 1536w, https:\/\/ecoturbino.world\/wp-content\/uploads\/2023\/12\/Logo-Gasthof-gross-2048x536.png 2048w, https:\/\/ecoturbino.world\/wp-content\/uploads\/2023\/12\/Logo-Gasthof-gross-240x63.png 240w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n                      <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n                        <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img decoding=\"async\" width=\"542\" height=\"362\" src=\"https:\/\/ecoturbino.world\/wp-content\/uploads\/2023\/12\/LOGO-Haslinger.png\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"1041,1036,1037,891,946,947,223,1373,1370,1367,1365,1362,1360,1359,1357,1355,1351,1349,1348,1347,1346,1342,1340,1330,1327,1274,1272,1267,1263,1253,1251,1250,1236,1234,1232,1230,1181,1167,1158,1067,966,965,964,962,961,960,959,958,957,955,953,952,950,949,948,935,934,933,932,919,918,916,915,914,913,911,904,897,894,892,874,871,868,867,865,864,843,828\" style=\"none\" lightbox=\"false\" type=\"masonry\" columns=\"5\" srcset=\"https:\/\/ecoturbino.world\/wp-content\/uploads\/2023\/12\/LOGO-Haslinger.png 542w, https:\/\/ecoturbino.world\/wp-content\/uploads\/2023\/12\/LOGO-Haslinger-240x160.png 240w\" sizes=\"(max-width: 542px) 100vw, 542px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n                      <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n                        <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img decoding=\"async\" width=\"149\" height=\"119\" src=\"https:\/\/ecoturbino.world\/wp-content\/uploads\/2024\/01\/Logo-Konigshof.png\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"1041,1036,1037,891,946,947,223,1373,1370,1367,1365,1362,1360,1359,1357,1355,1351,1349,1348,1347,1346,1342,1340,1330,1327,1274,1272,1267,1263,1253,1251,1250,1236,1234,1232,1230,1181,1167,1158,1067,966,965,964,962,961,960,959,958,957,955,953,952,950,949,948,935,934,933,932,919,918,916,915,914,913,911,904,897,894,892,874,871,868,867,865,864,843,828\" style=\"none\" lightbox=\"false\" type=\"masonry\" columns=\"5\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n                      <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n                        <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img decoding=\"async\" width=\"393\" height=\"180\" src=\"https:\/\/ecoturbino.world\/wp-content\/uploads\/2023\/12\/Logo-Reiterkogl.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"1041,1036,1037,891,946,947,223,1373,1370,1367,1365,1362,1360,1359,1357,1355,1351,1349,1348,1347,1346,1342,1340,1330,1327,1274,1272,1267,1263,1253,1251,1250,1236,1234,1232,1230,1181,1167,1158,1067,966,965,964,962,961,960,959,958,957,955,953,952,950,949,948,935,934,933,932,919,918,916,915,914,913,911,904,897,894,892,874,871,868,867,865,864,843,828\" style=\"none\" lightbox=\"false\" type=\"masonry\" columns=\"5\" srcset=\"https:\/\/ecoturbino.world\/wp-content\/uploads\/2023\/12\/Logo-Reiterkogl.jpg 393w, https:\/\/ecoturbino.world\/wp-content\/uploads\/2023\/12\/Logo-Reiterkogl-240x110.jpg 240w\" sizes=\"(max-width: 393px) 100vw, 393px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n                      <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n                        <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img decoding=\"async\" width=\"631\" height=\"495\" src=\"https:\/\/ecoturbino.world\/wp-content\/uploads\/2023\/12\/Logo-Landhaus.png\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"1041,1036,1037,891,946,947,223,1373,1370,1367,1365,1362,1360,1359,1357,1355,1351,1349,1348,1347,1346,1342,1340,1330,1327,1274,1272,1267,1263,1253,1251,1250,1236,1234,1232,1230,1181,1167,1158,1067,966,965,964,962,961,960,959,958,957,955,953,952,950,949,948,935,934,933,932,919,918,916,915,914,913,911,904,897,894,892,874,871,868,867,865,864,843,828\" style=\"none\" lightbox=\"false\" type=\"masonry\" columns=\"5\" srcset=\"https:\/\/ecoturbino.world\/wp-content\/uploads\/2023\/12\/Logo-Landhaus.png 631w, https:\/\/ecoturbino.world\/wp-content\/uploads\/2023\/12\/Logo-Landhaus-229x180.png 229w\" sizes=\"(max-width: 631px) 100vw, 631px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n                      <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n                        <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img decoding=\"async\" width=\"310\" height=\"180\" src=\"https:\/\/ecoturbino.world\/wp-content\/uploads\/2023\/12\/logo-sonnenburg-1.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"1041,1036,1037,891,946,947,223,1373,1370,1367,1365,1362,1360,1359,1357,1355,1351,1349,1348,1347,1346,1342,1340,1330,1327,1274,1272,1267,1263,1253,1251,1250,1236,1234,1232,1230,1181,1167,1158,1067,966,965,964,962,961,960,959,958,957,955,953,952,950,949,948,935,934,933,932,919,918,916,915,914,913,911,904,897,894,892,874,871,868,867,865,864,843,828\" style=\"none\" lightbox=\"false\" type=\"masonry\" columns=\"5\" srcset=\"https:\/\/ecoturbino.world\/wp-content\/uploads\/2023\/12\/logo-sonnenburg-1.jpg 310w, https:\/\/ecoturbino.world\/wp-content\/uploads\/2023\/12\/logo-sonnenburg-1-240x139.jpg 240w\" sizes=\"(max-width: 310px) 100vw, 310px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n                      <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n                        <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img decoding=\"async\" width=\"310\" height=\"180\" src=\"https:\/\/ecoturbino.world\/wp-content\/uploads\/2023\/12\/logo-sonnenburg.jpg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"1041,1036,1037,891,946,947,223,1373,1370,1367,1365,1362,1360,1359,1357,1355,1351,1349,1348,1347,1346,1342,1340,1330,1327,1274,1272,1267,1263,1253,1251,1250,1236,1234,1232,1230,1181,1167,1158,1067,966,965,964,962,961,960,959,958,957,955,953,952,950,949,948,935,934,933,932,919,918,916,915,914,913,911,904,897,894,892,874,871,868,867,865,864,843,828\" style=\"none\" lightbox=\"false\" type=\"masonry\" columns=\"5\" srcset=\"https:\/\/ecoturbino.world\/wp-content\/uploads\/2023\/12\/logo-sonnenburg.jpg 310w, https:\/\/ecoturbino.world\/wp-content\/uploads\/2023\/12\/logo-sonnenburg-240x139.jpg 240w\" sizes=\"(max-width: 310px) 100vw, 310px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n                      <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n                        <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img decoding=\"async\" width=\"162\" height=\"113\" src=\"https:\/\/ecoturbino.world\/wp-content\/uploads\/2023\/12\/LOGO-Schloss.png\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"1041,1036,1037,891,946,947,223,1373,1370,1367,1365,1362,1360,1359,1357,1355,1351,1349,1348,1347,1346,1342,1340,1330,1327,1274,1272,1267,1263,1253,1251,1250,1236,1234,1232,1230,1181,1167,1158,1067,966,965,964,962,961,960,959,958,957,955,953,952,950,949,948,935,934,933,932,919,918,916,915,914,913,911,904,897,894,892,874,871,868,867,865,864,843,828\" style=\"none\" lightbox=\"false\" type=\"masonry\" columns=\"5\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n                      <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n                        <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img decoding=\"async\" width=\"277\" height=\"202\" src=\"https:\/\/ecoturbino.world\/wp-content\/uploads\/2023\/12\/Logo-Rose.png\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"1041,1036,1037,891,946,947,223,1373,1370,1367,1365,1362,1360,1359,1357,1355,1351,1349,1348,1347,1346,1342,1340,1330,1327,1274,1272,1267,1263,1253,1251,1250,1236,1234,1232,1230,1181,1167,1158,1067,966,965,964,962,961,960,959,958,957,955,953,952,950,949,948,935,934,933,932,919,918,916,915,914,913,911,904,897,894,892,874,871,868,867,865,864,843,828\" style=\"none\" lightbox=\"false\" type=\"masonry\" columns=\"5\" srcset=\"https:\/\/ecoturbino.world\/wp-content\/uploads\/2023\/12\/Logo-Rose.png 277w, https:\/\/ecoturbino.world\/wp-content\/uploads\/2023\/12\/Logo-Rose-240x175.png 240w\" sizes=\"(max-width: 277px) 100vw, 277px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n                      <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n                        <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/ecoturbino.world\/wp-content\/uploads\/2023\/12\/logo-full.svg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"1041,1036,1037,891,946,947,223,1373,1370,1367,1365,1362,1360,1359,1357,1355,1351,1349,1348,1347,1346,1342,1340,1330,1327,1274,1272,1267,1263,1253,1251,1250,1236,1234,1232,1230,1181,1167,1158,1067,966,965,964,962,961,960,959,958,957,955,953,952,950,949,948,935,934,933,932,919,918,916,915,914,913,911,904,897,894,892,874,871,868,867,865,864,843,828\" style=\"none\" lightbox=\"false\" type=\"masonry\" columns=\"5\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n                      <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n                        <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img decoding=\"async\" width=\"1000\" height=\"77\" src=\"https:\/\/ecoturbino.world\/wp-content\/uploads\/2023\/12\/logo-Denk-1000x77.png\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"1041,1036,1037,891,946,947,223,1373,1370,1367,1365,1362,1360,1359,1357,1355,1351,1349,1348,1347,1346,1342,1340,1330,1327,1274,1272,1267,1263,1253,1251,1250,1236,1234,1232,1230,1181,1167,1158,1067,966,965,964,962,961,960,959,958,957,955,953,952,950,949,948,935,934,933,932,919,918,916,915,914,913,911,904,897,894,892,874,871,868,867,865,864,843,828\" style=\"none\" lightbox=\"false\" type=\"masonry\" columns=\"5\" srcset=\"https:\/\/ecoturbino.world\/wp-content\/uploads\/2023\/12\/logo-Denk-1000x77.png 1000w, https:\/\/ecoturbino.world\/wp-content\/uploads\/2023\/12\/logo-Denk-1500x116.png 1500w, https:\/\/ecoturbino.world\/wp-content\/uploads\/2023\/12\/logo-Denk-768x59.png 768w, https:\/\/ecoturbino.world\/wp-content\/uploads\/2023\/12\/logo-Denk-1536x119.png 1536w, https:\/\/ecoturbino.world\/wp-content\/uploads\/2023\/12\/logo-Denk-2048x158.png 2048w, https:\/\/ecoturbino.world\/wp-content\/uploads\/2023\/12\/logo-Denk-240x19.png 240w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n                      <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n                        <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img decoding=\"async\" width=\"367\" height=\"95\" src=\"https:\/\/ecoturbino.world\/wp-content\/uploads\/2023\/12\/airotel_logo.png\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"1041,1036,1037,891,946,947,223,1373,1370,1367,1365,1362,1360,1359,1357,1355,1351,1349,1348,1347,1346,1342,1340,1330,1327,1274,1272,1267,1263,1253,1251,1250,1236,1234,1232,1230,1181,1167,1158,1067,966,965,964,962,961,960,959,958,957,955,953,952,950,949,948,935,934,933,932,919,918,916,915,914,913,911,904,897,894,892,874,871,868,867,865,864,843,828\" style=\"none\" lightbox=\"false\" type=\"masonry\" columns=\"5\" srcset=\"https:\/\/ecoturbino.world\/wp-content\/uploads\/2023\/12\/airotel_logo.png 367w, https:\/\/ecoturbino.world\/wp-content\/uploads\/2023\/12\/airotel_logo-240x62.png 240w\" sizes=\"(max-width: 367px) 100vw, 367px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n                      <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n                        <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img decoding=\"async\" width=\"220\" height=\"140\" src=\"https:\/\/ecoturbino.world\/wp-content\/uploads\/2023\/12\/hotel_sonnblick-logo.png\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"1041,1036,1037,891,946,947,223,1373,1370,1367,1365,1362,1360,1359,1357,1355,1351,1349,1348,1347,1346,1342,1340,1330,1327,1274,1272,1267,1263,1253,1251,1250,1236,1234,1232,1230,1181,1167,1158,1067,966,965,964,962,961,960,959,958,957,955,953,952,950,949,948,935,934,933,932,919,918,916,915,914,913,911,904,897,894,892,874,871,868,867,865,864,843,828\" style=\"none\" lightbox=\"false\" type=\"masonry\" columns=\"5\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n                      <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n                        <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/ecoturbino.world\/wp-content\/uploads\/2023\/12\/johannesbad-medizin-logo-white.svg\" class=\"attachment-medium size-medium\" alt=\"Logotipo da Johannesbad Medizin\" ids=\"1041,1036,1037,891,946,947,223,1373,1370,1367,1365,1362,1360,1359,1357,1355,1351,1349,1348,1347,1346,1342,1340,1330,1327,1274,1272,1267,1263,1253,1251,1250,1236,1234,1232,1230,1181,1167,1158,1067,966,965,964,962,961,960,959,958,957,955,953,952,950,949,948,935,934,933,932,919,918,916,915,914,913,911,904,897,894,892,874,871,868,867,865,864,843,828\" style=\"none\" lightbox=\"false\" type=\"masonry\" columns=\"5\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p>Logotipo da Johannesbad Medizin<\/p>\n              <\/div>\n            <\/div>\n                      <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n                        <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img decoding=\"async\" width=\"275\" height=\"205\" src=\"https:\/\/ecoturbino.world\/wp-content\/uploads\/2023\/12\/birg-hotels-wien-logo.webp\" class=\"attachment-medium size-medium\" alt=\"Birg Hotels Wien Logotipo\" ids=\"1041,1036,1037,891,946,947,223,1373,1370,1367,1365,1362,1360,1359,1357,1355,1351,1349,1348,1347,1346,1342,1340,1330,1327,1274,1272,1267,1263,1253,1251,1250,1236,1234,1232,1230,1181,1167,1158,1067,966,965,964,962,961,960,959,958,957,955,953,952,950,949,948,935,934,933,932,919,918,916,915,914,913,911,904,897,894,892,874,871,868,867,865,864,843,828\" style=\"none\" lightbox=\"false\" type=\"masonry\" columns=\"5\" srcset=\"https:\/\/ecoturbino.world\/wp-content\/uploads\/2023\/12\/birg-hotels-wien-logo.webp 275w, https:\/\/ecoturbino.world\/wp-content\/uploads\/2023\/12\/birg-hotels-wien-logo-240x180.webp 240w\" sizes=\"(max-width: 275px) 100vw, 275px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p>Birg Hotels Wien Logotipo<\/p>\n              <\/div>\n            <\/div>\n                      <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n                        <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/ecoturbino.world\/wp-content\/uploads\/2023\/12\/schottenpoint-hotel-logo.svg\" class=\"attachment-medium size-medium\" alt=\"Log\u00f3tipo do Hotel am Schottenpoint\" ids=\"1041,1036,1037,891,946,947,223,1373,1370,1367,1365,1362,1360,1359,1357,1355,1351,1349,1348,1347,1346,1342,1340,1330,1327,1274,1272,1267,1263,1253,1251,1250,1236,1234,1232,1230,1181,1167,1158,1067,966,965,964,962,961,960,959,958,957,955,953,952,950,949,948,935,934,933,932,919,918,916,915,914,913,911,904,897,894,892,874,871,868,867,865,864,843,828\" style=\"none\" lightbox=\"false\" type=\"masonry\" columns=\"5\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p>Log\u00f3tipo do Hotel am Schottenpoint<\/p>\n              <\/div>\n            <\/div>\n                      <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n                        <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/ecoturbino.world\/wp-content\/uploads\/2023\/12\/eww-logo.svg\" class=\"attachment-medium size-medium\" alt=\"Log\u00f3tipo EWW\" ids=\"1041,1036,1037,891,946,947,223,1373,1370,1367,1365,1362,1360,1359,1357,1355,1351,1349,1348,1347,1346,1342,1340,1330,1327,1274,1272,1267,1263,1253,1251,1250,1236,1234,1232,1230,1181,1167,1158,1067,966,965,964,962,961,960,959,958,957,955,953,952,950,949,948,935,934,933,932,919,918,916,915,914,913,911,904,897,894,892,874,871,868,867,865,864,843,828\" style=\"none\" lightbox=\"false\" type=\"masonry\" columns=\"5\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p>Log\u00f3tipo EWW<\/p>\n              <\/div>\n            <\/div>\n                      <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n                        <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img decoding=\"async\" width=\"1000\" height=\"153\" src=\"https:\/\/ecoturbino.world\/wp-content\/uploads\/2023\/12\/Voestalpine-logo.svg\" class=\"attachment-medium size-medium\" alt=\"log\u00f3tipo da voestalpine\" ids=\"1041,1036,1037,891,946,947,223,1373,1370,1367,1365,1362,1360,1359,1357,1355,1351,1349,1348,1347,1346,1342,1340,1330,1327,1274,1272,1267,1263,1253,1251,1250,1236,1234,1232,1230,1181,1167,1158,1067,966,965,964,962,961,960,959,958,957,955,953,952,950,949,948,935,934,933,932,919,918,916,915,914,913,911,904,897,894,892,874,871,868,867,865,864,843,828\" style=\"none\" lightbox=\"false\" type=\"masonry\" columns=\"5\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p>log\u00f3tipo da voestalpine<\/p>\n              <\/div>\n            <\/div>\n                      <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n                        <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/ecoturbino.world\/wp-content\/uploads\/2023\/12\/harrys-home-logo.svg\" class=\"attachment-medium size-medium\" alt=\"casa do harry linz urfahr log\u00f3tipo\" ids=\"1041,1036,1037,891,946,947,223,1373,1370,1367,1365,1362,1360,1359,1357,1355,1351,1349,1348,1347,1346,1342,1340,1330,1327,1274,1272,1267,1263,1253,1251,1250,1236,1234,1232,1230,1181,1167,1158,1067,966,965,964,962,961,960,959,958,957,955,953,952,950,949,948,935,934,933,932,919,918,916,915,914,913,911,904,897,894,892,874,871,868,867,865,864,843,828\" style=\"none\" lightbox=\"false\" type=\"masonry\" columns=\"5\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p>casa do harry linz urfahr log\u00f3tipo<\/p>\n              <\/div>\n            <\/div>\n                      <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n                        <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/ecoturbino.world\/wp-content\/uploads\/2023\/12\/studentenwerk-logo.svg\" class=\"attachment-medium size-medium\" alt=\"Log\u00f3tipo da Studentenwerk Hagenberg\" ids=\"1041,1036,1037,891,946,947,223,1373,1370,1367,1365,1362,1360,1359,1357,1355,1351,1349,1348,1347,1346,1342,1340,1330,1327,1274,1272,1267,1263,1253,1251,1250,1236,1234,1232,1230,1181,1167,1158,1067,966,965,964,962,961,960,959,958,957,955,953,952,950,949,948,935,934,933,932,919,918,916,915,914,913,911,904,897,894,892,874,871,868,867,865,864,843,828\" style=\"none\" lightbox=\"false\" type=\"masonry\" columns=\"5\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p>Log\u00f3tipo da Studentenwerk Hagenberg<\/p>\n              <\/div>\n            <\/div>\n                      <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n                        <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/ecoturbino.world\/wp-content\/uploads\/2023\/12\/brennseehof-resort-logo.svg\" class=\"attachment-medium size-medium\" alt=\"Log\u00f3tipo do Brennerseehof Familien- &amp; Sportresort\" ids=\"1041,1036,1037,891,946,947,223,1373,1370,1367,1365,1362,1360,1359,1357,1355,1351,1349,1348,1347,1346,1342,1340,1330,1327,1274,1272,1267,1263,1253,1251,1250,1236,1234,1232,1230,1181,1167,1158,1067,966,965,964,962,961,960,959,958,957,955,953,952,950,949,948,935,934,933,932,919,918,916,915,914,913,911,904,897,894,892,874,871,868,867,865,864,843,828\" style=\"none\" lightbox=\"false\" type=\"masonry\" columns=\"5\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p>Log\u00f3tipo do Brennerseehof Familien- &amp; Sportresort<\/p>\n              <\/div>\n            <\/div>\n                      <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n                        <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/ecoturbino.world\/wp-content\/uploads\/2023\/12\/panorama-biohotel-logo.svg\" class=\"attachment-medium size-medium\" alt=\"Log\u00f3tipo do Bio Hotel Panorama\" ids=\"1041,1036,1037,891,946,947,223,1373,1370,1367,1365,1362,1360,1359,1357,1355,1351,1349,1348,1347,1346,1342,1340,1330,1327,1274,1272,1267,1263,1253,1251,1250,1236,1234,1232,1230,1181,1167,1158,1067,966,965,964,962,961,960,959,958,957,955,953,952,950,949,948,935,934,933,932,919,918,916,915,914,913,911,904,897,894,892,874,871,868,867,865,864,843,828\" style=\"none\" lightbox=\"false\" type=\"masonry\" columns=\"5\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p>Log\u00f3tipo do Bio Hotel Panorama<\/p>\n              <\/div>\n            <\/div>\n                      <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n                        <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/ecoturbino.world\/wp-content\/uploads\/2023\/12\/haeuserl-im-wald-landhotel-logo.svg\" class=\"attachment-medium size-medium\" alt=\"Log\u00f3tipo do H\u00e4userl im Wald Landhotel\" ids=\"1041,1036,1037,891,946,947,223,1373,1370,1367,1365,1362,1360,1359,1357,1355,1351,1349,1348,1347,1346,1342,1340,1330,1327,1274,1272,1267,1263,1253,1251,1250,1236,1234,1232,1230,1181,1167,1158,1067,966,965,964,962,961,960,959,958,957,955,953,952,950,949,948,935,934,933,932,919,918,916,915,914,913,911,904,897,894,892,874,871,868,867,865,864,843,828\" style=\"none\" lightbox=\"false\" type=\"masonry\" columns=\"5\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p>Log\u00f3tipo do H\u00e4userl im Wald Landhotel<\/p>\n              <\/div>\n            <\/div>\n                      <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n                        <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img decoding=\"async\" width=\"1000\" height=\"282\" src=\"https:\/\/ecoturbino.world\/wp-content\/uploads\/2023\/12\/logo-john-harris-red.svg\" class=\"attachment-medium size-medium\" alt=\"Log\u00f3tipo de fitness John Harris\" ids=\"1041,1036,1037,891,946,947,223,1373,1370,1367,1365,1362,1360,1359,1357,1355,1351,1349,1348,1347,1346,1342,1340,1330,1327,1274,1272,1267,1263,1253,1251,1250,1236,1234,1232,1230,1181,1167,1158,1067,966,965,964,962,961,960,959,958,957,955,953,952,950,949,948,935,934,933,932,919,918,916,915,914,913,911,904,897,894,892,874,871,868,867,865,864,843,828\" style=\"none\" lightbox=\"false\" type=\"masonry\" columns=\"5\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p>Log\u00f3tipo de fitness John Harris<\/p>\n              <\/div>\n            <\/div>\n                      <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n                        <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/ecoturbino.world\/wp-content\/uploads\/2023\/12\/zaglgut-chalets-suiten-logo.svg\" class=\"attachment-medium size-medium\" alt=\"Log\u00f3tipo Zaglgut\" ids=\"1041,1036,1037,891,946,947,223,1373,1370,1367,1365,1362,1360,1359,1357,1355,1351,1349,1348,1347,1346,1342,1340,1330,1327,1274,1272,1267,1263,1253,1251,1250,1236,1234,1232,1230,1181,1167,1158,1067,966,965,964,962,961,960,959,958,957,955,953,952,950,949,948,935,934,933,932,919,918,916,915,914,913,911,904,897,894,892,874,871,868,867,865,864,843,828\" style=\"none\" lightbox=\"false\" type=\"masonry\" columns=\"5\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p>Log\u00f3tipo Zaglgut<\/p>\n              <\/div>\n            <\/div>\n                      <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n                        <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/ecoturbino.world\/wp-content\/uploads\/2023\/12\/simms-hotel-logo.svg\" class=\"attachment-medium size-medium\" alt=\"Log\u00f3tipo do Simm&#039;s Hotel\" ids=\"1041,1036,1037,891,946,947,223,1373,1370,1367,1365,1362,1360,1359,1357,1355,1351,1349,1348,1347,1346,1342,1340,1330,1327,1274,1272,1267,1263,1253,1251,1250,1236,1234,1232,1230,1181,1167,1158,1067,966,965,964,962,961,960,959,958,957,955,953,952,950,949,948,935,934,933,932,919,918,916,915,914,913,911,904,897,894,892,874,871,868,867,865,864,843,828\" style=\"none\" lightbox=\"false\" type=\"masonry\" columns=\"5\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p>Log\u00f3tipo do Simm's Hotel<\/p>\n              <\/div>\n            <\/div>\n                      <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n                        <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/ecoturbino.world\/wp-content\/uploads\/2023\/12\/falk-seehotels-logo.svg\" class=\"attachment-medium size-medium\" alt=\"Log\u00f3tipo Falk Seehotels\" ids=\"1041,1036,1037,891,946,947,223,1373,1370,1367,1365,1362,1360,1359,1357,1355,1351,1349,1348,1347,1346,1342,1340,1330,1327,1274,1272,1267,1263,1253,1251,1250,1236,1234,1232,1230,1181,1167,1158,1067,966,965,964,962,961,960,959,958,957,955,953,952,950,949,948,935,934,933,932,919,918,916,915,914,913,911,904,897,894,892,874,871,868,867,865,864,843,828\" style=\"none\" lightbox=\"false\" type=\"masonry\" columns=\"5\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p>Log\u00f3tipo Falk Seehotels<\/p>\n              <\/div>\n            <\/div>\n                      <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n                        <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/ecoturbino.world\/wp-content\/uploads\/2023\/12\/strandhafer-hotel-logo.svg\" class=\"attachment-medium size-medium\" alt=\"Log\u00f3tipo do Strandhafer Aparthotel\" ids=\"1041,1036,1037,891,946,947,223,1373,1370,1367,1365,1362,1360,1359,1357,1355,1351,1349,1348,1347,1346,1342,1340,1330,1327,1274,1272,1267,1263,1253,1251,1250,1236,1234,1232,1230,1181,1167,1158,1067,966,965,964,962,961,960,959,958,957,955,953,952,950,949,948,935,934,933,932,919,918,916,915,914,913,911,904,897,894,892,874,871,868,867,865,864,843,828\" style=\"none\" lightbox=\"false\" type=\"masonry\" columns=\"5\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p>Log\u00f3tipo do Strandhafer Aparthotel<\/p>\n              <\/div>\n            <\/div>\n                      <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n                        <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/ecoturbino.world\/wp-content\/uploads\/2023\/12\/khg-linz-logo.svg\" class=\"attachment-medium size-medium\" alt=\"KHG Linz wohnheim Franz J\u00e4gerst\u00e4tter Log\u00f3tipo\" ids=\"1041,1036,1037,891,946,947,223,1373,1370,1367,1365,1362,1360,1359,1357,1355,1351,1349,1348,1347,1346,1342,1340,1330,1327,1274,1272,1267,1263,1253,1251,1250,1236,1234,1232,1230,1181,1167,1158,1067,966,965,964,962,961,960,959,958,957,955,953,952,950,949,948,935,934,933,932,919,918,916,915,914,913,911,904,897,894,892,874,871,868,867,865,864,843,828\" style=\"none\" lightbox=\"false\" type=\"masonry\" columns=\"5\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p>KHG Linz wohnheim Franz J\u00e4gerst\u00e4tter Log\u00f3tipo<\/p>\n              <\/div>\n            <\/div>\n                      <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n                        <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img decoding=\"async\" width=\"1000\" height=\"353\" src=\"https:\/\/ecoturbino.world\/wp-content\/uploads\/2023\/12\/Hotel_Goisererhof_Logo_Superior.svg\" class=\"attachment-medium size-medium\" alt=\"Log\u00f3tipo do Hotel Goisererhof\" ids=\"1041,1036,1037,891,946,947,223,1373,1370,1367,1365,1362,1360,1359,1357,1355,1351,1349,1348,1347,1346,1342,1340,1330,1327,1274,1272,1267,1263,1253,1251,1250,1236,1234,1232,1230,1181,1167,1158,1067,966,965,964,962,961,960,959,958,957,955,953,952,950,949,948,935,934,933,932,919,918,916,915,914,913,911,904,897,894,892,874,871,868,867,865,864,843,828\" style=\"none\" lightbox=\"false\" type=\"masonry\" columns=\"5\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p>Log\u00f3tipo do Hotel Goisererhof<\/p>\n              <\/div>\n            <\/div>\n                      <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n                        <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img decoding=\"async\" width=\"275\" height=\"205\" src=\"https:\/\/ecoturbino.world\/wp-content\/uploads\/2023\/12\/hollweger-hotel-logo.png\" class=\"attachment-medium size-medium\" alt=\"Log\u00f3tipo do Hotel Hollweger\" ids=\"1041,1036,1037,891,946,947,223,1373,1370,1367,1365,1362,1360,1359,1357,1355,1351,1349,1348,1347,1346,1342,1340,1330,1327,1274,1272,1267,1263,1253,1251,1250,1236,1234,1232,1230,1181,1167,1158,1067,966,965,964,962,961,960,959,958,957,955,953,952,950,949,948,935,934,933,932,919,918,916,915,914,913,911,904,897,894,892,874,871,868,867,865,864,843,828\" style=\"none\" lightbox=\"false\" type=\"masonry\" columns=\"5\" srcset=\"https:\/\/ecoturbino.world\/wp-content\/uploads\/2023\/12\/hollweger-hotel-logo.png 275w, https:\/\/ecoturbino.world\/wp-content\/uploads\/2023\/12\/hollweger-hotel-logo-240x180.png 240w\" sizes=\"(max-width: 275px) 100vw, 275px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p>Log\u00f3tipo do Hotel Hollweger<\/p>\n              <\/div>\n            <\/div>\n                      <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n                        <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/ecoturbino.world\/wp-content\/uploads\/2023\/12\/injoy-logo.svg\" class=\"attachment-medium size-medium\" alt=\"Log\u00f3tipo Injoy\" ids=\"1041,1036,1037,891,946,947,223,1373,1370,1367,1365,1362,1360,1359,1357,1355,1351,1349,1348,1347,1346,1342,1340,1330,1327,1274,1272,1267,1263,1253,1251,1250,1236,1234,1232,1230,1181,1167,1158,1067,966,965,964,962,961,960,959,958,957,955,953,952,950,949,948,935,934,933,932,919,918,916,915,914,913,911,904,897,894,892,874,871,868,867,865,864,843,828\" style=\"none\" lightbox=\"false\" type=\"masonry\" columns=\"5\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p>Log\u00f3tipo Injoy<\/p>\n              <\/div>\n            <\/div>\n                      <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n                        <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/ecoturbino.world\/wp-content\/uploads\/2023\/12\/sankt-magdalena-logo.svg\" class=\"attachment-medium size-medium\" alt=\"Log\u00f3tipo da Bildungshaus Sankt Magdalena\" ids=\"1041,1036,1037,891,946,947,223,1373,1370,1367,1365,1362,1360,1359,1357,1355,1351,1349,1348,1347,1346,1342,1340,1330,1327,1274,1272,1267,1263,1253,1251,1250,1236,1234,1232,1230,1181,1167,1158,1067,966,965,964,962,961,960,959,958,957,955,953,952,950,949,948,935,934,933,932,919,918,916,915,914,913,911,904,897,894,892,874,871,868,867,865,864,843,828\" style=\"none\" lightbox=\"false\" type=\"masonry\" columns=\"5\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p>Log\u00f3tipo da Bildungshaus Sankt Magdalena<\/p>\n              <\/div>\n            <\/div>\n                      <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n                        <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img decoding=\"async\" width=\"1000\" height=\"427\" src=\"https:\/\/ecoturbino.world\/wp-content\/uploads\/2023\/12\/zauchenseehof-logo-blau.svg\" class=\"attachment-medium size-medium\" alt=\"Log\u00f3tipo do Hotel Zauchenseehof\" ids=\"1041,1036,1037,891,946,947,223,1373,1370,1367,1365,1362,1360,1359,1357,1355,1351,1349,1348,1347,1346,1342,1340,1330,1327,1274,1272,1267,1263,1253,1251,1250,1236,1234,1232,1230,1181,1167,1158,1067,966,965,964,962,961,960,959,958,957,955,953,952,950,949,948,935,934,933,932,919,918,916,915,914,913,911,904,897,894,892,874,871,868,867,865,864,843,828\" style=\"none\" lightbox=\"false\" type=\"masonry\" columns=\"5\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p>Log\u00f3tipo do Hotel Zauchenseehof<\/p>\n              <\/div>\n            <\/div>\n                      <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n                        <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/ecoturbino.world\/wp-content\/uploads\/2023\/12\/kurhotel-sassnitz-logo.svg\" class=\"attachment-medium size-medium\" alt=\"Log\u00f3tipo do Sassnitz Kurhotel\" ids=\"1041,1036,1037,891,946,947,223,1373,1370,1367,1365,1362,1360,1359,1357,1355,1351,1349,1348,1347,1346,1342,1340,1330,1327,1274,1272,1267,1263,1253,1251,1250,1236,1234,1232,1230,1181,1167,1158,1067,966,965,964,962,961,960,959,958,957,955,953,952,950,949,948,935,934,933,932,919,918,916,915,914,913,911,904,897,894,892,874,871,868,867,865,864,843,828\" style=\"none\" lightbox=\"false\" type=\"masonry\" columns=\"5\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p>Log\u00f3tipo do Sassnitz Kurhotel<\/p>\n              <\/div>\n            <\/div>\n                      <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n                        <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/ecoturbino.world\/wp-content\/uploads\/2023\/12\/forsthofgut-logo.svg\" class=\"attachment-medium size-medium\" alt=\"Log\u00f3tipo do Forsthofgut Naturhotel\" ids=\"1041,1036,1037,891,946,947,223,1373,1370,1367,1365,1362,1360,1359,1357,1355,1351,1349,1348,1347,1346,1342,1340,1330,1327,1274,1272,1267,1263,1253,1251,1250,1236,1234,1232,1230,1181,1167,1158,1067,966,965,964,962,961,960,959,958,957,955,953,952,950,949,948,935,934,933,932,919,918,916,915,914,913,911,904,897,894,892,874,871,868,867,865,864,843,828\" style=\"none\" lightbox=\"false\" type=\"masonry\" columns=\"5\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p>Log\u00f3tipo do Forsthofgut Naturhotel<\/p>\n              <\/div>\n            <\/div>\n                      <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n                        <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/ecoturbino.world\/wp-content\/uploads\/2023\/12\/schloss-wartegg-logo.svg\" class=\"attachment-medium size-medium\" alt=\"Log\u00f3tipo Schloss Wartegg\" ids=\"1041,1036,1037,891,946,947,223,1373,1370,1367,1365,1362,1360,1359,1357,1355,1351,1349,1348,1347,1346,1342,1340,1330,1327,1274,1272,1267,1263,1253,1251,1250,1236,1234,1232,1230,1181,1167,1158,1067,966,965,964,962,961,960,959,958,957,955,953,952,950,949,948,935,934,933,932,919,918,916,915,914,913,911,904,897,894,892,874,871,868,867,865,864,843,828\" style=\"none\" lightbox=\"false\" type=\"masonry\" columns=\"5\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p>Log\u00f3tipo Schloss Wartegg<\/p>\n              <\/div>\n            <\/div>\n                      <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n                        <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img decoding=\"async\" width=\"275\" height=\"205\" src=\"https:\/\/ecoturbino.world\/wp-content\/uploads\/2023\/12\/ambassador-wien-logo.webp\" class=\"attachment-medium size-medium\" alt=\"Log\u00f3tipo do Hotel Ambassador\" ids=\"1041,1036,1037,891,946,947,223,1373,1370,1367,1365,1362,1360,1359,1357,1355,1351,1349,1348,1347,1346,1342,1340,1330,1327,1274,1272,1267,1263,1253,1251,1250,1236,1234,1232,1230,1181,1167,1158,1067,966,965,964,962,961,960,959,958,957,955,953,952,950,949,948,935,934,933,932,919,918,916,915,914,913,911,904,897,894,892,874,871,868,867,865,864,843,828\" style=\"none\" lightbox=\"false\" type=\"masonry\" columns=\"5\" srcset=\"https:\/\/ecoturbino.world\/wp-content\/uploads\/2023\/12\/ambassador-wien-logo.webp 275w, https:\/\/ecoturbino.world\/wp-content\/uploads\/2023\/12\/ambassador-wien-logo-240x180.webp 240w\" sizes=\"(max-width: 275px) 100vw, 275px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p>Log\u00f3tipo do Hotel Ambassador<\/p>\n              <\/div>\n            <\/div>\n                      <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n                        <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/ecoturbino.world\/wp-content\/uploads\/2023\/12\/vortuna-logo.svg\" class=\"attachment-medium size-medium\" alt=\"Log\u00f3tipo Vortuna\" ids=\"1041,1036,1037,891,946,947,223,1373,1370,1367,1365,1362,1360,1359,1357,1355,1351,1349,1348,1347,1346,1342,1340,1330,1327,1274,1272,1267,1263,1253,1251,1250,1236,1234,1232,1230,1181,1167,1158,1067,966,965,964,962,961,960,959,958,957,955,953,952,950,949,948,935,934,933,932,919,918,916,915,914,913,911,904,897,894,892,874,871,868,867,865,864,843,828\" style=\"none\" lightbox=\"false\" type=\"masonry\" columns=\"5\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p>Log\u00f3tipo Vortuna<\/p>\n              <\/div>\n            <\/div>\n                      <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n                        <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/ecoturbino.world\/wp-content\/uploads\/2023\/12\/am-kogl-logo.svg\" class=\"attachment-medium size-medium\" alt=\"Log\u00f3tipo Am Kogl\" ids=\"1041,1036,1037,891,946,947,223,1373,1370,1367,1365,1362,1360,1359,1357,1355,1351,1349,1348,1347,1346,1342,1340,1330,1327,1274,1272,1267,1263,1253,1251,1250,1236,1234,1232,1230,1181,1167,1158,1067,966,965,964,962,961,960,959,958,957,955,953,952,950,949,948,935,934,933,932,919,918,916,915,914,913,911,904,897,894,892,874,871,868,867,865,864,843,828\" style=\"none\" lightbox=\"false\" type=\"masonry\" columns=\"5\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p>Log\u00f3tipo Am Kogl<\/p>\n              <\/div>\n            <\/div>\n                      <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n                        <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img decoding=\"async\" width=\"1000\" height=\"420\" src=\"https:\/\/ecoturbino.world\/wp-content\/uploads\/2023\/12\/jkh-logo.svg\" class=\"attachment-medium size-medium\" alt=\"Log\u00f3tipo Johannes Kepler Heim\" ids=\"1041,1036,1037,891,946,947,223,1373,1370,1367,1365,1362,1360,1359,1357,1355,1351,1349,1348,1347,1346,1342,1340,1330,1327,1274,1272,1267,1263,1253,1251,1250,1236,1234,1232,1230,1181,1167,1158,1067,966,965,964,962,961,960,959,958,957,955,953,952,950,949,948,935,934,933,932,919,918,916,915,914,913,911,904,897,894,892,874,871,868,867,865,864,843,828\" style=\"none\" lightbox=\"false\" type=\"masonry\" columns=\"5\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p>Log\u00f3tipo Johannes Kepler Heim<\/p>\n              <\/div>\n            <\/div>\n                      <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n                        <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/ecoturbino.world\/wp-content\/uploads\/2023\/12\/ferdl-denk-logo.svg\" class=\"attachment-medium size-medium\" alt=\"Log\u00f3tipo Ferdl Denk\" ids=\"1041,1036,1037,891,946,947,223,1373,1370,1367,1365,1362,1360,1359,1357,1355,1351,1349,1348,1347,1346,1342,1340,1330,1327,1274,1272,1267,1263,1253,1251,1250,1236,1234,1232,1230,1181,1167,1158,1067,966,965,964,962,961,960,959,958,957,955,953,952,950,949,948,935,934,933,932,919,918,916,915,914,913,911,904,897,894,892,874,871,868,867,865,864,843,828\" style=\"none\" lightbox=\"false\" type=\"masonry\" columns=\"5\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p>Log\u00f3tipo Ferdl Denk<\/p>\n              <\/div>\n            <\/div>\n                      <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n                        <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/ecoturbino.world\/wp-content\/uploads\/2023\/12\/donauwirt-hotel-logo.svg\" class=\"attachment-medium size-medium\" alt=\"Logotipo Donauwirt Wachau\" ids=\"1041,1036,1037,891,946,947,223,1373,1370,1367,1365,1362,1360,1359,1357,1355,1351,1349,1348,1347,1346,1342,1340,1330,1327,1274,1272,1267,1263,1253,1251,1250,1236,1234,1232,1230,1181,1167,1158,1067,966,965,964,962,961,960,959,958,957,955,953,952,950,949,948,935,934,933,932,919,918,916,915,914,913,911,904,897,894,892,874,871,868,867,865,864,843,828\" style=\"none\" lightbox=\"false\" type=\"masonry\" columns=\"5\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p>Logotipo Donauwirt Wachau<\/p>\n              <\/div>\n            <\/div>\n                      <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n                        <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/ecoturbino.world\/wp-content\/uploads\/2023\/12\/weinspitz-boutiquehotel-logo.svg\" class=\"attachment-medium size-medium\" alt=\"Log\u00f3tipo do Weinspitz Boutiquehotel\" ids=\"1041,1036,1037,891,946,947,223,1373,1370,1367,1365,1362,1360,1359,1357,1355,1351,1349,1348,1347,1346,1342,1340,1330,1327,1274,1272,1267,1263,1253,1251,1250,1236,1234,1232,1230,1181,1167,1158,1067,966,965,964,962,961,960,959,958,957,955,953,952,950,949,948,935,934,933,932,919,918,916,915,914,913,911,904,897,894,892,874,871,868,867,865,864,843,828\" style=\"none\" lightbox=\"false\" type=\"masonry\" columns=\"5\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p>Log\u00f3tipo do Weinspitz Boutiquehotel<\/p>\n              <\/div>\n            <\/div>\n                      <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n                        <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/ecoturbino.world\/wp-content\/uploads\/2023\/12\/proge-logo.svg\" class=\"attachment-medium size-medium\" alt=\"Log\u00f3tipo PROGE\" ids=\"1041,1036,1037,891,946,947,223,1373,1370,1367,1365,1362,1360,1359,1357,1355,1351,1349,1348,1347,1346,1342,1340,1330,1327,1274,1272,1267,1263,1253,1251,1250,1236,1234,1232,1230,1181,1167,1158,1067,966,965,964,962,961,960,959,958,957,955,953,952,950,949,948,935,934,933,932,919,918,916,915,914,913,911,904,897,894,892,874,871,868,867,865,864,843,828\" style=\"none\" lightbox=\"false\" type=\"masonry\" columns=\"5\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p>Log\u00f3tipo PROGE<\/p>\n              <\/div>\n            <\/div>\n                      <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n                        <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img decoding=\"async\" width=\"275\" height=\"205\" src=\"https:\/\/ecoturbino.world\/wp-content\/uploads\/2023\/12\/achalm-hotel-logo.webp\" class=\"attachment-medium size-medium\" alt=\"Log\u00f3tipo do Hotel Achalm\" ids=\"1041,1036,1037,891,946,947,223,1373,1370,1367,1365,1362,1360,1359,1357,1355,1351,1349,1348,1347,1346,1342,1340,1330,1327,1274,1272,1267,1263,1253,1251,1250,1236,1234,1232,1230,1181,1167,1158,1067,966,965,964,962,961,960,959,958,957,955,953,952,950,949,948,935,934,933,932,919,918,916,915,914,913,911,904,897,894,892,874,871,868,867,865,864,843,828\" style=\"none\" lightbox=\"false\" type=\"masonry\" columns=\"5\" srcset=\"https:\/\/ecoturbino.world\/wp-content\/uploads\/2023\/12\/achalm-hotel-logo.webp 275w, https:\/\/ecoturbino.world\/wp-content\/uploads\/2023\/12\/achalm-hotel-logo-240x180.webp 240w\" sizes=\"(max-width: 275px) 100vw, 275px\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p>Log\u00f3tipo do Hotel Achalm<\/p>\n              <\/div>\n            <\/div>\n                      <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n                        <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/ecoturbino.world\/wp-content\/uploads\/2023\/12\/tropenklinik-lechler-logo.svg\" class=\"attachment-medium size-medium\" alt=\"Log\u00f3tipo do Tropenklink Paul Lechler Krankenhaus\" ids=\"1041,1036,1037,891,946,947,223,1373,1370,1367,1365,1362,1360,1359,1357,1355,1351,1349,1348,1347,1346,1342,1340,1330,1327,1274,1272,1267,1263,1253,1251,1250,1236,1234,1232,1230,1181,1167,1158,1067,966,965,964,962,961,960,959,958,957,955,953,952,950,949,948,935,934,933,932,919,918,916,915,914,913,911,904,897,894,892,874,871,868,867,865,864,843,828\" style=\"none\" lightbox=\"false\" type=\"masonry\" columns=\"5\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p>Log\u00f3tipo do Tropenklink Paul Lechler Krankenhaus<\/p>\n              <\/div>\n            <\/div>\n                      <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n                        <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/ecoturbino.world\/wp-content\/uploads\/2023\/12\/fuerstenhof-hotel-logo.svg\" class=\"attachment-medium size-medium\" alt=\"Log\u00f3tipo do Hotel F\u00fcrtsenhof\" ids=\"1041,1036,1037,891,946,947,223,1373,1370,1367,1365,1362,1360,1359,1357,1355,1351,1349,1348,1347,1346,1342,1340,1330,1327,1274,1272,1267,1263,1253,1251,1250,1236,1234,1232,1230,1181,1167,1158,1067,966,965,964,962,961,960,959,958,957,955,953,952,950,949,948,935,934,933,932,919,918,916,915,914,913,911,904,897,894,892,874,871,868,867,865,864,843,828\" style=\"none\" lightbox=\"false\" type=\"masonry\" columns=\"5\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p>Log\u00f3tipo do Hotel F\u00fcrtsenhof<\/p>\n              <\/div>\n            <\/div>\n                      <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n                        <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/ecoturbino.world\/wp-content\/uploads\/2023\/12\/elements-obersdorf-logo.svg\" class=\"attachment-medium size-medium\" alt=\"elementos Logotipo Obersdorf\" ids=\"1041,1036,1037,891,946,947,223,1373,1370,1367,1365,1362,1360,1359,1357,1355,1351,1349,1348,1347,1346,1342,1340,1330,1327,1274,1272,1267,1263,1253,1251,1250,1236,1234,1232,1230,1181,1167,1158,1067,966,965,964,962,961,960,959,958,957,955,953,952,950,949,948,935,934,933,932,919,918,916,915,914,913,911,904,897,894,892,874,871,868,867,865,864,843,828\" style=\"none\" lightbox=\"false\" type=\"masonry\" columns=\"5\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p>elementos Logotipo Obersdorf<\/p>\n              <\/div>\n            <\/div>\n                      <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n                        <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/ecoturbino.world\/wp-content\/uploads\/2023\/12\/buchenhoehe-alpenresidenz-logo.svg\" class=\"attachment-medium size-medium\" alt=\"Logotipo Alpenresidenz Buchenh\u00f6he\" ids=\"1041,1036,1037,891,946,947,223,1373,1370,1367,1365,1362,1360,1359,1357,1355,1351,1349,1348,1347,1346,1342,1340,1330,1327,1274,1272,1267,1263,1253,1251,1250,1236,1234,1232,1230,1181,1167,1158,1067,966,965,964,962,961,960,959,958,957,955,953,952,950,949,948,935,934,933,932,919,918,916,915,914,913,911,904,897,894,892,874,871,868,867,865,864,843,828\" style=\"none\" lightbox=\"false\" type=\"masonry\" columns=\"5\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p>Logotipo Alpenresidenz Buchenh\u00f6he<\/p>\n              <\/div>\n            <\/div>\n                      <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n                        <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img decoding=\"async\" width=\"1000\" height=\"145\" src=\"https:\/\/ecoturbino.world\/wp-content\/uploads\/2023\/12\/logo-rupertus.svg\" class=\"attachment-medium size-medium\" alt=\"\" ids=\"1041,1036,1037,891,946,947,223,1373,1370,1367,1365,1362,1360,1359,1357,1355,1351,1349,1348,1347,1346,1342,1340,1330,1327,1274,1272,1267,1263,1253,1251,1250,1236,1234,1232,1230,1181,1167,1158,1067,966,965,964,962,961,960,959,958,957,955,953,952,950,949,948,935,934,933,932,919,918,916,915,914,913,911,904,897,894,892,874,871,868,867,865,864,843,828\" style=\"none\" lightbox=\"false\" type=\"masonry\" columns=\"5\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p><\/p>\n              <\/div>\n            <\/div>\n                      <\/div>\n         <\/div><div class=\"gallery-col col\" >\n          <div class=\"col-inner\">\n                        <div class=\"box has-hover gallery-box box-none\">\n              <div class=\"box-image\" >\n                <img decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/ecoturbino.world\/wp-content\/uploads\/2023\/12\/freigeist-hotel-goettingen-logo.svg\" class=\"attachment-medium size-medium\" alt=\"Log\u00f3tipo Freigeist G\u00f6ttingen Innenstadt\" ids=\"1041,1036,1037,891,946,947,223,1373,1370,1367,1365,1362,1360,1359,1357,1355,1351,1349,1348,1347,1346,1342,1340,1330,1327,1274,1272,1267,1263,1253,1251,1250,1236,1234,1232,1230,1181,1167,1158,1067,966,965,964,962,961,960,959,958,957,955,953,952,950,949,948,935,934,933,932,919,918,916,915,914,913,911,904,897,894,892,874,871,868,867,865,864,843,828\" style=\"none\" lightbox=\"false\" type=\"masonry\" columns=\"5\" \/>                                                              <\/div>\n              <div class=\"box-text text-left\" >\n                 <p>Log\u00f3tipo Freigeist G\u00f6ttingen Innenstadt<\/p>\n              <\/div>\n            <\/div>\n                      <\/div>\n         <\/div><\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":9,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-blank.php","meta":{"inline_featured_image":false,"footnotes":""},"class_list":["post-1437","page","type-page","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/ecoturbino.world\/pt\/wp-json\/wp\/v2\/pages\/1437","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ecoturbino.world\/pt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ecoturbino.world\/pt\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ecoturbino.world\/pt\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ecoturbino.world\/pt\/wp-json\/wp\/v2\/comments?post=1437"}],"version-history":[{"count":0,"href":"https:\/\/ecoturbino.world\/pt\/wp-json\/wp\/v2\/pages\/1437\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ecoturbino.world\/pt\/wp-json\/wp\/v2\/media\/9"}],"wp:attachment":[{"href":"https:\/\/ecoturbino.world\/pt\/wp-json\/wp\/v2\/media?parent=1437"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}